{"id":3253,"date":"2015-08-27T08:30:57","date_gmt":"2015-08-27T06:30:57","guid":{"rendered":"http:\/\/blog.soloptical.net\/?p=3253"},"modified":"2017-09-27T17:03:52","modified_gmt":"2017-09-27T15:03:52","slug":"gafas-para-leer","status":"publish","type":"post","link":"https:\/\/soloptical.net\/blog\/gafas-para-leer\/","title":{"rendered":"Gafas para leer"},"content":{"rendered":"<p>Forman parte de ti. Es tu ratito de relax: t\u00fa y tus inseparables\u00a0 <strong>gafas para leer<\/strong> ese libro que tanto deseas acabar te esperan encima de tu mesita de noche.<\/p>\n<p>Conc\u00e9dete un ratito. Coge tus gafas y tu libro y pi\u00e9rdete imaginando esa <strong><em>historia de aventuras, amores o \u201cintr\u00edngulis\u201d\u00a0 policiacos<\/em><\/strong> que hacen que te acuestes m\u00e1s tarde de la cuenta.\u00a0 (y te acuerdes demasiado al sonar el despertador!).<\/p>\n<p>Y es que, cada gafa parece ir <strong>ligada a esa persona que se esconde detr\u00e1s de los libros<\/strong>&#8230; Hoy en Blog a primera a primera vista, te dejamos algunas de recomendaciones:<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Para aquellos que le guste leer&#8230;su propia historia<\/strong><\/p>\n<p><em>\u201cLibro de las historias tuyas\u00a0 y m\u00edas y de nadie m\u00e1s\u201d.<\/em> \u00a0Las gafas para leer, y releer,\u00a0 vuestra historia, no podr\u00edan ser otras que <a href=\"http:\/\/www.soloptical.net\/gafas-en-promocion\/\"><strong>SXT MARBELLA.<\/strong> <\/a>Carism\u00e1ticas, llenas de color e inigualables, esta colecci\u00f3n de gafas no dejar\u00e1 indiferente a nadie, al igual que historia ;-).<\/p>\n<p>&nbsp;<\/p>\n<div class=\"post-thumb clearfix\">\n    <figure class=\"featured-thumbnail thumbnail large\">\n        <div class=\"hider-page\"><\/div>\n        <a class=\"image-wrap image-popup-no-margins\"  href=\"http:\/\/blog.soloptical.net\/wp-content\/uploads\/2015\/08\/gafas-sxtmarbella.jpg\" data-rel=\"Photo\">\n            <img src=\"http:\/\/blog.soloptical.net\/wp-content\/uploads\/2015\/08\/gafas-sxtmarbella.jpg\" alt=\"photo\" \/>\n            <span class=\"zoom-icon\"><\/span>\n        <\/a>\n    <\/figure>\n    <div class=\"clear\"><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<div class=\"post-thumb clearfix\">\n    <figure class=\"featured-thumbnail thumbnail large\">\n        <div class=\"hider-page\"><\/div>\n        <a class=\"image-wrap image-popup-no-margins\"  href=\"http:\/\/blog.soloptical.net\/wp-content\/uploads\/2015\/08\/gafas-sxtmarbella-ni\u00f1os.jpg\" data-rel=\"Photo\">\n            <img src=\"http:\/\/blog.soloptical.net\/wp-content\/uploads\/2015\/08\/gafas-sxtmarbella-ni\u00f1os.jpg\" alt=\"photo\" \/>\n            <span class=\"zoom-icon\"><\/span>\n        <\/a>\n    <\/figure>\n    <div class=\"clear\"><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p>Los m\u00e1s peque\u00f1os podr\u00e1n disfrutar de una amena lectura con sus gafas para leer SXT Marbella. Extra ligeras con dise\u00f1os \u00fanicos para los m\u00e1s \u201cqueridos\u201d de la casa<strong>.<a href=\"http:\/\/www.soloptical.net\/gafas-en-promocion\/\"> Colecci\u00f3n exclusiva de Soloptical.<\/a><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Para los m\u00e1s urbanos<\/strong><\/p>\n<p>Los libros de papel, ya no son lo tuyo.\u00a0 En el metro, bus&#8230;tu e-book es uno m\u00e1s de tus accesorios y tus gafas para leerlo van a <strong>acordes a tu estilo.<\/strong> Cl\u00e1sicas por fuera, atrevidas por dentro te proponemos\u00a0 este modelo de <strong>gafas del Potro<\/strong>, con un toque diferente para salirte del\u00a0 lo cl\u00e1sico sin ser extravagante.<\/p>\n<div class=\"post-thumb clearfix\">\n    <figure class=\"featured-thumbnail thumbnail large\">\n        <div class=\"hider-page\"><\/div>\n        <a class=\"image-wrap image-popup-no-margins\"  href=\"http:\/\/blog.soloptical.net\/wp-content\/uploads\/2015\/08\/gafas-elpotro.jpg\" data-rel=\"Photo\">\n            <img src=\"http:\/\/blog.soloptical.net\/wp-content\/uploads\/2015\/08\/gafas-elpotro.jpg\" alt=\"photo\" \/>\n            <span class=\"zoom-icon\"><\/span>\n        <\/a>\n    <\/figure>\n    <div class=\"clear\"><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Para los amantes de la historia: l\u00edneas sencillas y cl\u00e1sicas<\/strong><\/p>\n<p>Tu curiosidad por saber qu\u00e9 nos ha llevado a la actualidad de hoy es el tema m\u00e1s recurrido en tu biblioteca de libros.<\/p>\n<p>La l\u00ednea Venus de gafas\u00a0 har\u00e1 que leas a\u00fan mejor\u00a0 el secreto egipcio de Napole\u00f3n, desde donde parte el libro de la Pir\u00e1mide inmortal. \u00a0\u00a0Pr\u00e1cticas y funcionales, resultan ideales como \u201csegunda\u201d\u00a0 las gafas para leer.<\/p>\n<div class=\"post-thumb clearfix\">\n    <figure class=\"featured-thumbnail thumbnail large\">\n        <div class=\"hider-page\"><\/div>\n        <a class=\"image-wrap image-popup-no-margins\"  href=\"http:\/\/blog.soloptical.net\/wp-content\/uploads\/2015\/08\/gafas-venus.jpg\" data-rel=\"Photo\">\n            <img src=\"http:\/\/blog.soloptical.net\/wp-content\/uploads\/2015\/08\/gafas-venus.jpg\" alt=\"photo\" \/>\n            <span class=\"zoom-icon\"><\/span>\n        <\/a>\n    <\/figure>\n    <div class=\"clear\"><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Y tu, \u00bfqu\u00e9 <strong><em>libro tienes entre manos?.<\/em><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Si quieres consultar m\u00e1s info:<\/p>\n<p><strong>Modelos de gafas &#8211;<\/strong>&gt;\u00a0<a href=\"http:\/\/www.soloptical.net\/ofertas\/\">http:\/\/www.soloptical.net\/ofertas\/<\/a><\/p>\n<p><strong>Libros que aparecen en este post:<\/strong><\/p>\n<p>http:\/\/www.mrwonderfulshop.es\/es\/libro-de-las-historias-tuyas-y-mias-y-de-nadie-mas.html<\/p>\n<p>http:\/\/www.javiersierra.com\/w\/libros\/la-piramide-inmortal\/<\/p>\n<p>http:\/\/www.casadellibro.com\/libro-cuando-me-siento-querido\/9788467522020\/1186804<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Forman parte de ti. Es tu ratito de relax: t\u00fa y tus inseparables\u00a0 gafas para leer ese libro que tanto deseas acabar te esperan encima de tu mesita de noche. Conc\u00e9dete un ratito. Coge tus gafas y tu libro y pi\u00e9rdete imaginando esa historia de aventuras, amores o \u201cintr\u00edngulis\u201d\u00a0 policiacos que hacen que te acuestes&nbsp;<a href=\"https:\/\/soloptical.net\/blog\/gafas-para-leer\/\" class=\"read-more\">Continua leyendo<\/a><\/p>\n","protected":false},"author":10,"featured_media":3477,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[80,116],"tags":[113],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gafas para leer - Blog a primera vista<\/title>\n<meta name=\"description\" content=\"Tu y tus inseparables gafas para leer ese libro que tanto deseas acabar te esperan encima de tu mesita de noche!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/soloptical.net\/blog\/gafas-para-leer\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gafas para leer - Blog a primera vista\" \/>\n<meta property=\"og:description\" content=\"Tu y tus inseparables gafas para leer ese libro que tanto deseas acabar te esperan encima de tu mesita de noche!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/soloptical.net\/blog\/gafas-para-leer\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog a primera vista\" \/>\n<meta property=\"article:published_time\" content=\"2015-08-27T06:30:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-09-27T15:03:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2015\/10\/ana-locking-soloptical1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"940\" \/>\n\t<meta property=\"og:image:height\" content=\"788\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mario Andrade\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/soloptical.net\/blog\/#website\",\"url\":\"https:\/\/soloptical.net\/blog\/\",\"name\":\"Blog a primera vista\",\"description\":\"by soloptical\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/soloptical.net\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/soloptical.net\/blog\/gafas-para-leer\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2015\/10\/ana-locking-soloptical1.jpg\",\"contentUrl\":\"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2015\/10\/ana-locking-soloptical1.jpg\",\"width\":940,\"height\":788},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/soloptical.net\/blog\/gafas-para-leer\/#webpage\",\"url\":\"https:\/\/soloptical.net\/blog\/gafas-para-leer\/\",\"name\":\"Gafas para leer - Blog a primera vista\",\"isPartOf\":{\"@id\":\"https:\/\/soloptical.net\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/soloptical.net\/blog\/gafas-para-leer\/#primaryimage\"},\"datePublished\":\"2015-08-27T06:30:57+00:00\",\"dateModified\":\"2017-09-27T15:03:52+00:00\",\"author\":{\"@id\":\"https:\/\/soloptical.net\/blog\/#\/schema\/person\/ff9996614428adaccc3f660afa419f7c\"},\"description\":\"Tu y tus inseparables gafas para leer ese libro que tanto deseas acabar te esperan encima de tu mesita de noche!\",\"breadcrumb\":{\"@id\":\"https:\/\/soloptical.net\/blog\/gafas-para-leer\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/soloptical.net\/blog\/gafas-para-leer\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/soloptical.net\/blog\/gafas-para-leer\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/soloptical.net\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gafas para leer\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/soloptical.net\/blog\/#\/schema\/person\/ff9996614428adaccc3f660afa419f7c\",\"name\":\"Mario Andrade\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/soloptical.net\/blog\/#personlogo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/bd6aca70d99c4eb6eb996fb36630b1d3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/bd6aca70d99c4eb6eb996fb36630b1d3?s=96&d=mm&r=g\",\"caption\":\"Mario Andrade\"},\"sameAs\":[\"http:\/\/www.soloptical.com\"],\"url\":\"https:\/\/soloptical.net\/blog\/author\/mario\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gafas para leer - Blog a primera vista","description":"Tu y tus inseparables gafas para leer ese libro que tanto deseas acabar te esperan encima de tu mesita de noche!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/soloptical.net\/blog\/gafas-para-leer\/","og_locale":"es_ES","og_type":"article","og_title":"Gafas para leer - Blog a primera vista","og_description":"Tu y tus inseparables gafas para leer ese libro que tanto deseas acabar te esperan encima de tu mesita de noche!","og_url":"https:\/\/soloptical.net\/blog\/gafas-para-leer\/","og_site_name":"Blog a primera vista","article_published_time":"2015-08-27T06:30:57+00:00","article_modified_time":"2017-09-27T15:03:52+00:00","og_image":[{"width":940,"height":788,"url":"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2015\/10\/ana-locking-soloptical1.jpg","type":"image\/jpeg"}],"twitter_card":"summary","twitter_misc":{"Escrito por":"Mario Andrade","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/soloptical.net\/blog\/#website","url":"https:\/\/soloptical.net\/blog\/","name":"Blog a primera vista","description":"by soloptical","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/soloptical.net\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","@id":"https:\/\/soloptical.net\/blog\/gafas-para-leer\/#primaryimage","inLanguage":"es","url":"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2015\/10\/ana-locking-soloptical1.jpg","contentUrl":"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2015\/10\/ana-locking-soloptical1.jpg","width":940,"height":788},{"@type":"WebPage","@id":"https:\/\/soloptical.net\/blog\/gafas-para-leer\/#webpage","url":"https:\/\/soloptical.net\/blog\/gafas-para-leer\/","name":"Gafas para leer - Blog a primera vista","isPartOf":{"@id":"https:\/\/soloptical.net\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/soloptical.net\/blog\/gafas-para-leer\/#primaryimage"},"datePublished":"2015-08-27T06:30:57+00:00","dateModified":"2017-09-27T15:03:52+00:00","author":{"@id":"https:\/\/soloptical.net\/blog\/#\/schema\/person\/ff9996614428adaccc3f660afa419f7c"},"description":"Tu y tus inseparables gafas para leer ese libro que tanto deseas acabar te esperan encima de tu mesita de noche!","breadcrumb":{"@id":"https:\/\/soloptical.net\/blog\/gafas-para-leer\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/soloptical.net\/blog\/gafas-para-leer\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/soloptical.net\/blog\/gafas-para-leer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/soloptical.net\/blog\/"},{"@type":"ListItem","position":2,"name":"Gafas para leer"}]},{"@type":"Person","@id":"https:\/\/soloptical.net\/blog\/#\/schema\/person\/ff9996614428adaccc3f660afa419f7c","name":"Mario Andrade","image":{"@type":"ImageObject","@id":"https:\/\/soloptical.net\/blog\/#personlogo","inLanguage":"es","url":"https:\/\/secure.gravatar.com\/avatar\/bd6aca70d99c4eb6eb996fb36630b1d3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bd6aca70d99c4eb6eb996fb36630b1d3?s=96&d=mm&r=g","caption":"Mario Andrade"},"sameAs":["http:\/\/www.soloptical.com"],"url":"https:\/\/soloptical.net\/blog\/author\/mario\/"}]}},"_links":{"self":[{"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/posts\/3253"}],"collection":[{"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/comments?post=3253"}],"version-history":[{"count":9,"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/posts\/3253\/revisions"}],"predecessor-version":[{"id":4680,"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/posts\/3253\/revisions\/4680"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/media\/3477"}],"wp:attachment":[{"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/media?parent=3253"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/categories?post=3253"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/tags?post=3253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}