{"id":3270,"date":"2015-09-03T08:45:00","date_gmt":"2015-09-03T06:45:00","guid":{"rendered":"http:\/\/blog.soloptical.net\/?p=3270"},"modified":"2015-09-04T11:43:05","modified_gmt":"2015-09-04T09:43:05","slug":"nueva-coleccion-sxt-marbella","status":"publish","type":"post","link":"https:\/\/soloptical.net\/blog\/nueva-coleccion-sxt-marbella\/","title":{"rendered":"Nueva colecci\u00f3n: SXT Marbella"},"content":{"rendered":"<p>La familia de gafas graduadas de SXT Marbella llega para marcar tendencia en esta temporada oto\u00f1al. El colorido propio de esta \u00e9poca se refleja en la nueva colecci\u00f3n:\u00a0SXT Marbella.<strong><strong>\u00a0<\/strong><\/strong>\u00a0L\u00edneas redondeadas, ocres y alg\u00fan toque deslumbrante protagonizan la l\u00ednea m\u00e1s carism\u00e1tica de <a href=\"http:\/\/www.soloptical.net\/\">Soloptical.<\/a><\/p>\n<p><em>\u00bfLa vemos?<\/em><\/p>\n<p>&nbsp;<\/p>\n<h2><strong><u>#1Gafas&#8230;Trendy \u201cnerds\u00bb\u00a0?\u00a0<\/u><\/strong><\/h2>\n<p>Las gafas, graduadas o no, se han convertido en un <strong>complemento<\/strong> m\u00e1s. Mientras que en \u00e9pocas anteriores estaba relacionados con los <strong><em>\u201cnerds\u201d<\/em><\/strong> , cada vez son m\u00e1s fashionistas que se unen a esta tendencia. No es raro tener varios modelos gafas <em>seg\u00fan el look que luzcas cada d\u00eda.<\/em><\/p>\n<div class=\"post-thumb clearfix\">\n    <figure class=\"featured-thumbnail thumbnail large\">\n        <div class=\"hider-page\"><\/div>\n        <a class=\"image-wrap image-popup-no-margins\"  href=\"http:\/\/blog.soloptical.net\/wp-content\/uploads\/2015\/09\/gafas-graduadas-Jenna-Lions.jpg\" data-rel=\"Photo\">\n            <img src=\"http:\/\/blog.soloptical.net\/wp-content\/uploads\/2015\/09\/gafas-graduadas-Jenna-Lions.jpg\" alt=\"photo\" \/>\n            <span class=\"zoom-icon\"><\/span>\n        <\/a>\n    <\/figure>\n    <div class=\"clear\"><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p>Ejemplo de ello es Jenny Lions, directora creativa de J.Crew.<\/p>\n<div class=\"post-thumb clearfix\">\n    <figure class=\"featured-thumbnail thumbnail large\">\n        <div class=\"hider-page\"><\/div>\n        <a class=\"image-wrap image-popup-no-margins\"  href=\"http:\/\/blog.soloptical.net\/wp-content\/uploads\/2015\/09\/gafas-graduadas-redondas-hombre.jpg\" data-rel=\"Photo\">\n            <img src=\"http:\/\/blog.soloptical.net\/wp-content\/uploads\/2015\/09\/gafas-graduadas-redondas-hombre.jpg\" alt=\"photo\" \/>\n            <span class=\"zoom-icon\"><\/span>\n        <\/a>\n    <\/figure>\n    <div class=\"clear\"><\/div>\n<\/div>\n<p>Unisex, este complemento es com\u00fan entre hombres y mujeres.<\/p>\n<blockquote>Cada vez son m\u00e1s fashionistas que se \u00fanen a esta tendencia. No es raro tener varios modelos \u00a0gafas seg\u00fan el look que luzcas cada d\u00eda<\/blockquote><!-- blockquote (end) -->\n<p>&nbsp;<\/p>\n<h2><strong><u>#2 Nuevas\u00a0versi\u00f3n del efecto Havana<\/u><\/strong><\/h2>\n<p>Es un hecho: las <strong><em>gafas redondas<\/em><\/strong> son tendencia, tanto para hombre como mujer. NUEVA\u00a0colecci\u00f3n:\u00a0<strong>SXT Marbella:\u00a0<\/strong>toques nacarados\u00a0 y acabos met\u00e1licos los nuevos modelos SXT funden lo cl\u00e1sico\u00a0 y moderno para dar personalidad a tu estilo.\u00a0 Pru\u00e9bate todos los modelos <strong>aqu\u00ed\u00a0<\/strong><\/p>\n<div class=\"post-thumb clearfix\">\n    <figure class=\"featured-thumbnail thumbnail large\">\n        <div class=\"hider-page\"><\/div>\n        <a class=\"image-wrap image-popup-no-margins\"  href=\"http:\/\/blog.soloptical.net\/wp-content\/uploads\/2015\/09\/nueva-coleccion-gafas-sxtmarbella.jpg\" data-rel=\"Photo\">\n            <img src=\"http:\/\/blog.soloptical.net\/wp-content\/uploads\/2015\/09\/nueva-coleccion-gafas-sxtmarbella.jpg\" alt=\"photo\" \/>\n            <span class=\"zoom-icon\"><\/span>\n        <\/a>\n    <\/figure>\n    <div class=\"clear\"><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h2><strong><u>#3\u00a0Linea cl\u00e1sica SXT Marbella<\/u><\/strong><\/h2>\n<p>La nueva colecci\u00f3n de gafas\u00a0 <strong>SXT Marbella<\/strong> trae consigo una reinvenci\u00f3n de su cl\u00e1sico: monturas semi al aire con notas de color: rojos, marrones, carey, negro&#8230;<\/p>\n<p>Perfecto para un<em> working\u00a0 outfit!<\/em><\/p>\n<div class=\"post-thumb clearfix\">\n    <figure class=\"featured-thumbnail thumbnail large\">\n        <div class=\"hider-page\"><\/div>\n        <a class=\"image-wrap image-popup-no-margins\"  href=\"http:\/\/blog.soloptical.net\/wp-content\/uploads\/2015\/09\/sxtmarbella-cl\u00e1sicas.jpg\" data-rel=\"Photo\">\n            <img src=\"http:\/\/blog.soloptical.net\/wp-content\/uploads\/2015\/09\/sxtmarbella-cl\u00e1sicas.jpg\" alt=\"photo\" \/>\n            <span class=\"zoom-icon\"><\/span>\n        <\/a>\n    <\/figure>\n    <div class=\"clear\"><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<h2><strong><u>#4 \u00bfPreparad@s para el fin de semana? Arri\u00e9sgate!\u00a0<\/u><\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p>No pasas desapercibido: tu lista de spotify, tu \u00a0libro&#8230;o tu montura de\u00a0 gafas. Igual ocurre con estas\u00a0 nuevas monturas: l\u00edneas \u00a0sencillas con un toque <em>discretamente<\/em> <strong>rockero.<\/strong><\/p>\n<div class=\"post-thumb clearfix\">\n    <figure class=\"featured-thumbnail thumbnail large\">\n        <div class=\"hider-page\"><\/div>\n        <a class=\"image-wrap image-popup-no-margins\"  href=\"http:\/\/blog.soloptical.net\/wp-content\/uploads\/2015\/09\/nueva-coleccion-gafassxt.jpg\" data-rel=\"Photo\">\n            <img src=\"http:\/\/blog.soloptical.net\/wp-content\/uploads\/2015\/09\/nueva-coleccion-gafassxt.jpg\" alt=\"photo\" \/>\n            <span class=\"zoom-icon\"><\/span>\n        <\/a>\n    <\/figure>\n    <div class=\"clear\"><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p>Todos estos modelos y\u00a0 m\u00e1s podr\u00e1s encontrarlos en tu punto <a href=\"http:\/\/www.soloptical.net\/listado-de-tiendas\/\">Soloptical m\u00e1s cercano.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La familia de gafas graduadas de SXT Marbella llega para marcar tendencia en esta temporada oto\u00f1al. El colorido propio de esta \u00e9poca se refleja en la nueva colecci\u00f3n:\u00a0SXT Marbella.\u00a0\u00a0L\u00edneas redondeadas, ocres y alg\u00fan toque deslumbrante protagonizan la l\u00ednea m\u00e1s carism\u00e1tica de Soloptical. \u00bfLa vemos? &nbsp; #1Gafas&#8230;Trendy \u201cnerds\u00bb\u00a0?\u00a0 Las gafas, graduadas o no, se han convertido&nbsp;<a href=\"https:\/\/soloptical.net\/blog\/nueva-coleccion-sxt-marbella\/\" class=\"read-more\">Continua leyendo<\/a><\/p>\n","protected":false},"author":10,"featured_media":3281,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[80,4],"tags":[114],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Nueva colecci\u00f3n: SXT Marbella<\/title>\n<meta name=\"description\" content=\"SXT Marbella, la l\u00ednea de gafas m\u00e1s carism\u00e1tica de Soloptical nos presenta su nueva colecci\u00f3n en gafas graduadas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/soloptical.net\/blog\/nueva-coleccion-sxt-marbella\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nueva colecci\u00f3n: SXT Marbella\" \/>\n<meta property=\"og:description\" content=\"SXT Marbella, la l\u00ednea de gafas m\u00e1s carism\u00e1tica de Soloptical nos presenta su nueva colecci\u00f3n en gafas graduadas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/soloptical.net\/blog\/nueva-coleccion-sxt-marbella\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog a primera vista\" \/>\n<meta property=\"article:published_time\" content=\"2015-09-03T06:45:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-09-04T09:43:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2015\/09\/sxtmarbella-redondas-negras-1024x683.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mario Andrade\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/soloptical.net\/blog\/#website\",\"url\":\"https:\/\/soloptical.net\/blog\/\",\"name\":\"Blog a primera vista\",\"description\":\"by soloptical\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/soloptical.net\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/soloptical.net\/blog\/nueva-coleccion-sxt-marbella\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2015\/09\/sxtmarbella-redondas-negras.jpg\",\"contentUrl\":\"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2015\/09\/sxtmarbella-redondas-negras.jpg\",\"width\":4272,\"height\":2848},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/soloptical.net\/blog\/nueva-coleccion-sxt-marbella\/#webpage\",\"url\":\"https:\/\/soloptical.net\/blog\/nueva-coleccion-sxt-marbella\/\",\"name\":\"Nueva colecci\u00f3n: SXT Marbella\",\"isPartOf\":{\"@id\":\"https:\/\/soloptical.net\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/soloptical.net\/blog\/nueva-coleccion-sxt-marbella\/#primaryimage\"},\"datePublished\":\"2015-09-03T06:45:00+00:00\",\"dateModified\":\"2015-09-04T09:43:05+00:00\",\"author\":{\"@id\":\"https:\/\/soloptical.net\/blog\/#\/schema\/person\/ff9996614428adaccc3f660afa419f7c\"},\"description\":\"SXT Marbella, la l\u00ednea de gafas m\u00e1s carism\u00e1tica de Soloptical nos presenta su nueva colecci\u00f3n en gafas graduadas.\",\"breadcrumb\":{\"@id\":\"https:\/\/soloptical.net\/blog\/nueva-coleccion-sxt-marbella\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/soloptical.net\/blog\/nueva-coleccion-sxt-marbella\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/soloptical.net\/blog\/nueva-coleccion-sxt-marbella\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/soloptical.net\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nueva colecci\u00f3n: SXT Marbella\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/soloptical.net\/blog\/#\/schema\/person\/ff9996614428adaccc3f660afa419f7c\",\"name\":\"Mario Andrade\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/soloptical.net\/blog\/#personlogo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/bd6aca70d99c4eb6eb996fb36630b1d3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/bd6aca70d99c4eb6eb996fb36630b1d3?s=96&d=mm&r=g\",\"caption\":\"Mario Andrade\"},\"sameAs\":[\"http:\/\/www.soloptical.com\"],\"url\":\"https:\/\/soloptical.net\/blog\/author\/mario\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nueva colecci\u00f3n: SXT Marbella","description":"SXT Marbella, la l\u00ednea de gafas m\u00e1s carism\u00e1tica de Soloptical nos presenta su nueva colecci\u00f3n en gafas graduadas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/soloptical.net\/blog\/nueva-coleccion-sxt-marbella\/","og_locale":"es_ES","og_type":"article","og_title":"Nueva colecci\u00f3n: SXT Marbella","og_description":"SXT Marbella, la l\u00ednea de gafas m\u00e1s carism\u00e1tica de Soloptical nos presenta su nueva colecci\u00f3n en gafas graduadas.","og_url":"https:\/\/soloptical.net\/blog\/nueva-coleccion-sxt-marbella\/","og_site_name":"Blog a primera vista","article_published_time":"2015-09-03T06:45:00+00:00","article_modified_time":"2015-09-04T09:43:05+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2015\/09\/sxtmarbella-redondas-negras-1024x683.jpg","type":"image\/jpeg"}],"twitter_card":"summary","twitter_misc":{"Escrito por":"Mario Andrade","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/soloptical.net\/blog\/#website","url":"https:\/\/soloptical.net\/blog\/","name":"Blog a primera vista","description":"by soloptical","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/soloptical.net\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","@id":"https:\/\/soloptical.net\/blog\/nueva-coleccion-sxt-marbella\/#primaryimage","inLanguage":"es","url":"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2015\/09\/sxtmarbella-redondas-negras.jpg","contentUrl":"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2015\/09\/sxtmarbella-redondas-negras.jpg","width":4272,"height":2848},{"@type":"WebPage","@id":"https:\/\/soloptical.net\/blog\/nueva-coleccion-sxt-marbella\/#webpage","url":"https:\/\/soloptical.net\/blog\/nueva-coleccion-sxt-marbella\/","name":"Nueva colecci\u00f3n: SXT Marbella","isPartOf":{"@id":"https:\/\/soloptical.net\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/soloptical.net\/blog\/nueva-coleccion-sxt-marbella\/#primaryimage"},"datePublished":"2015-09-03T06:45:00+00:00","dateModified":"2015-09-04T09:43:05+00:00","author":{"@id":"https:\/\/soloptical.net\/blog\/#\/schema\/person\/ff9996614428adaccc3f660afa419f7c"},"description":"SXT Marbella, la l\u00ednea de gafas m\u00e1s carism\u00e1tica de Soloptical nos presenta su nueva colecci\u00f3n en gafas graduadas.","breadcrumb":{"@id":"https:\/\/soloptical.net\/blog\/nueva-coleccion-sxt-marbella\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/soloptical.net\/blog\/nueva-coleccion-sxt-marbella\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/soloptical.net\/blog\/nueva-coleccion-sxt-marbella\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/soloptical.net\/blog\/"},{"@type":"ListItem","position":2,"name":"Nueva colecci\u00f3n: SXT Marbella"}]},{"@type":"Person","@id":"https:\/\/soloptical.net\/blog\/#\/schema\/person\/ff9996614428adaccc3f660afa419f7c","name":"Mario Andrade","image":{"@type":"ImageObject","@id":"https:\/\/soloptical.net\/blog\/#personlogo","inLanguage":"es","url":"https:\/\/secure.gravatar.com\/avatar\/bd6aca70d99c4eb6eb996fb36630b1d3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bd6aca70d99c4eb6eb996fb36630b1d3?s=96&d=mm&r=g","caption":"Mario Andrade"},"sameAs":["http:\/\/www.soloptical.com"],"url":"https:\/\/soloptical.net\/blog\/author\/mario\/"}]}},"_links":{"self":[{"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/posts\/3270"}],"collection":[{"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/comments?post=3270"}],"version-history":[{"count":21,"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/posts\/3270\/revisions"}],"predecessor-version":[{"id":3312,"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/posts\/3270\/revisions\/3312"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/media\/3281"}],"wp:attachment":[{"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/media?parent=3270"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/categories?post=3270"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/tags?post=3270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}