{"id":4472,"date":"2017-02-10T18:04:12","date_gmt":"2017-02-10T17:04:12","guid":{"rendered":"http:\/\/blog.soloptical.net\/?p=4472"},"modified":"2017-09-27T12:23:09","modified_gmt":"2017-09-27T10:23:09","slug":"que-regalar-para-san-valentin","status":"publish","type":"post","link":"https:\/\/soloptical.net\/blog\/que-regalar-para-san-valentin\/","title":{"rendered":"\u00bfQu\u00e9 regalar para San Valent\u00edn?"},"content":{"rendered":"<h3>\u00bfQu\u00e9 significa para ti el d\u00eda de San Valent\u00edn?<\/h3>\n<p>Son muchos los que piensan que es un d\u00eda inventado por los centros comerciales y las tiendas para aumentar las tiendas y otros muchos son los que piensan que San Valent\u00edn es el d\u00eda m\u00e1s rom\u00e1ntico del a\u00f1o en el que no puede faltar un detalla de la persona que m\u00e1s quieres o para esa persona.<\/p>\n<p>Por todos los motivos anteriores hoy hemos decidido realizar un post para daros algunas ideas de qu\u00e9 regalar para San Valent\u00edn.<\/p>\n<p>Estamos a Domingo y s\u00f3lo quedan dos d\u00edas para el gran d\u00edas as\u00ed que tenemos dos opciones: o buscamos algo en una tienda online que nos garantice que vamos a tener el pedido en casa el martes como por ejemplo <a href=\"http:\/\/bit.ly\/2kszMWh\" target=\"_blank\">nuestra tienda online <\/a>o decidimos hacer un regalo por nosotros mismos que adem\u00e1s seguro que le encantar\u00e1.<\/p>\n<h3><strong>1. Velada Rom\u00e1ntica<\/strong><\/h3>\n<p>\u00bfEres aficionado a la cocina? \u00bfQu\u00e9 te parece si para el Martes organizas una cena en casa a la luz de las velas con el plato preferido de tu pareja? Seguro que le encanta el detalle \ud83d\ude09 Ah! No te olvides del postre \ud83d\ude42<\/p>\n<h3><strong>2. Caja de los sentidos<\/strong><\/h3>\n<p>Esta quiz\u00e1s sea la opci\u00f3n que m\u00e1s trabajo conlleve pero quiz\u00e1s la que m\u00e1s ilusi\u00f3n le haga. Es una caja de los sentidos donde, teniendo en cuenta los 5 sentidos, tendr\u00e1s que introducir diferentes regalos. Por ejemplo,<\/p>\n<ul>\n<li><strong>Olfato<\/strong> &#8211;&gt; Puedes regalarle su colonia favorita o una vela arom\u00e1tica que os recuerde a alg\u00fan momento juntos.<\/li>\n<li><strong>Vista<\/strong> &#8211;&gt; \u00bfQu\u00e9 te parece vuestra foto favorita en un marco o todos los recuerdos como entradas de conciertos, cine o el tiquet del primer caf\u00e9 en un marco de cristal?<\/li>\n<li><strong>O\u00eddo<\/strong> &#8211;&gt; Es el momento para que le grabes vuestra canci\u00f3n favorita o una canci\u00f3n que te recuerde a tu pareja.<\/li>\n<li><strong>Gusto<\/strong> &#8211;&gt; \u00bfY si optas por su postre favorito o por sus gominolas favoritas?<\/li>\n<li><strong>Tacto<\/strong> &#8211;&gt; Un vale por un masaje. Ya sea dado por ti o en un hamman o un spa<\/li>\n<\/ul>\n<h3><strong>3. Caja de experiencia<\/strong><\/h3>\n<p>\u00bfConoces esas cajas de experiencia que venden en librer\u00edas y grandes centros comerciales donde compras la experiencia y el que recibe el regalo lo elige? Es un bonito detalle y adem\u00e1s ten\u00e9is un a\u00f1o entero para canjearlo \ud83d\ude09<\/p>\n<h3><strong>4. Ese regalo que lleva meses pidiendo<img loading=\"lazy\" class=\" size-medium wp-image-4477 alignright\" src=\"http:\/\/blog.soloptical.net\/wp-content\/uploads\/2017\/02\/PUBLI-FACEBOOK-300x300.jpg\" alt=\"PUBLI-FACEBOOK\" width=\"300\" height=\"300\" srcset=\"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2017\/02\/PUBLI-FACEBOOK-300x300.jpg 300w, https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2017\/02\/PUBLI-FACEBOOK-150x150.jpg 150w, https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2017\/02\/PUBLI-FACEBOOK-1024x1024.jpg 1024w, https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2017\/02\/PUBLI-FACEBOOK-735x735.jpg 735w, https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2017\/02\/PUBLI-FACEBOOK-430x430.jpg 430w, https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2017\/02\/PUBLI-FACEBOOK-80x80.jpg 80w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/strong><\/h3>\n<p>\u00bfPasa por un escaparate y se para sin decirte nada? \u00bfSe ha enamorado de esas Ray Ban tan caras que vio en la tienda? Ahora tienes la oportunidad de conseguirlas m\u00e1s baratas en nuestra <a href=\"http:\/\/bit.ly\/2kszMWh\" target=\"_blank\"><strong>Tienda Online<\/strong> <\/a>con el c\u00f3digo: <strong>SANVALENTIN<\/strong> y obtendr\u00e1s un <strong>15% de Descuento<\/strong><\/p>\n<p>Esperamos haberos ayudado un poquito m\u00e1s! \ud83d\ude09<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfQu\u00e9 significa para ti el d\u00eda de San Valent\u00edn? Son muchos los que piensan que es un d\u00eda inventado por los centros comerciales y las tiendas para aumentar las tiendas y otros muchos son los que piensan que San Valent\u00edn es el d\u00eda m\u00e1s rom\u00e1ntico del a\u00f1o en el que no puede faltar un detalla&nbsp;<a href=\"https:\/\/soloptical.net\/blog\/que-regalar-para-san-valentin\/\" class=\"read-more\">Continua leyendo<\/a><\/p>\n","protected":false},"author":10,"featured_media":4475,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[253,283],"tags":[294],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfQu\u00e9 regalar para San Valent\u00edn? - Blog a primera vista<\/title>\n<meta name=\"description\" content=\"S\u00f3lo quedan d\u00edas para San Valent\u00edn \u00a1Os traemos varias ideas para que sepas qu\u00e9 regalar para san Valentin y pases un gran d\u00eda!\u00a1Entra y desc\u00fabrelo!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/soloptical.net\/blog\/que-regalar-para-san-valentin\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQu\u00e9 regalar para San Valent\u00edn? - Blog a primera vista\" \/>\n<meta property=\"og:description\" content=\"S\u00f3lo quedan d\u00edas para San Valent\u00edn \u00a1Os traemos varias ideas para que sepas qu\u00e9 regalar para san Valentin y pases un gran d\u00eda!\u00a1Entra y desc\u00fabrelo!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/soloptical.net\/blog\/que-regalar-para-san-valentin\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog a primera vista\" \/>\n<meta property=\"article:published_time\" content=\"2017-02-10T17:04:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-09-27T10:23:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2017\/02\/PUBLI-FB-SOLOPTICAL-SAN-VALENTIN-ONLINE-01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2500\" \/>\n\t<meta property=\"og:image:height\" content=\"1306\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mario Andrade\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/soloptical.net\/blog\/#website\",\"url\":\"https:\/\/soloptical.net\/blog\/\",\"name\":\"Blog a primera vista\",\"description\":\"by soloptical\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/soloptical.net\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/soloptical.net\/blog\/que-regalar-para-san-valentin\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2017\/02\/PUBLI-FB-SOLOPTICAL-SAN-VALENTIN-ONLINE-01.jpg\",\"contentUrl\":\"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2017\/02\/PUBLI-FB-SOLOPTICAL-SAN-VALENTIN-ONLINE-01.jpg\",\"width\":2500,\"height\":1306},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/soloptical.net\/blog\/que-regalar-para-san-valentin\/#webpage\",\"url\":\"https:\/\/soloptical.net\/blog\/que-regalar-para-san-valentin\/\",\"name\":\"\u00bfQu\u00e9 regalar para San Valent\u00edn? - Blog a primera vista\",\"isPartOf\":{\"@id\":\"https:\/\/soloptical.net\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/soloptical.net\/blog\/que-regalar-para-san-valentin\/#primaryimage\"},\"datePublished\":\"2017-02-10T17:04:12+00:00\",\"dateModified\":\"2017-09-27T10:23:09+00:00\",\"author\":{\"@id\":\"https:\/\/soloptical.net\/blog\/#\/schema\/person\/ff9996614428adaccc3f660afa419f7c\"},\"description\":\"S\u00f3lo quedan d\u00edas para San Valent\u00edn \u00a1Os traemos varias ideas para que sepas qu\u00e9 regalar para san Valentin y pases un gran d\u00eda!\u00a1Entra y desc\u00fabrelo!\",\"breadcrumb\":{\"@id\":\"https:\/\/soloptical.net\/blog\/que-regalar-para-san-valentin\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/soloptical.net\/blog\/que-regalar-para-san-valentin\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/soloptical.net\/blog\/que-regalar-para-san-valentin\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/soloptical.net\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfQu\u00e9 regalar para San Valent\u00edn?\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/soloptical.net\/blog\/#\/schema\/person\/ff9996614428adaccc3f660afa419f7c\",\"name\":\"Mario Andrade\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/soloptical.net\/blog\/#personlogo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/bd6aca70d99c4eb6eb996fb36630b1d3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/bd6aca70d99c4eb6eb996fb36630b1d3?s=96&d=mm&r=g\",\"caption\":\"Mario Andrade\"},\"sameAs\":[\"http:\/\/www.soloptical.com\"],\"url\":\"https:\/\/soloptical.net\/blog\/author\/mario\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQu\u00e9 regalar para San Valent\u00edn? - Blog a primera vista","description":"S\u00f3lo quedan d\u00edas para San Valent\u00edn \u00a1Os traemos varias ideas para que sepas qu\u00e9 regalar para san Valentin y pases un gran d\u00eda!\u00a1Entra y desc\u00fabrelo!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/soloptical.net\/blog\/que-regalar-para-san-valentin\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfQu\u00e9 regalar para San Valent\u00edn? - Blog a primera vista","og_description":"S\u00f3lo quedan d\u00edas para San Valent\u00edn \u00a1Os traemos varias ideas para que sepas qu\u00e9 regalar para san Valentin y pases un gran d\u00eda!\u00a1Entra y desc\u00fabrelo!","og_url":"https:\/\/soloptical.net\/blog\/que-regalar-para-san-valentin\/","og_site_name":"Blog a primera vista","article_published_time":"2017-02-10T17:04:12+00:00","article_modified_time":"2017-09-27T10:23:09+00:00","og_image":[{"width":2500,"height":1306,"url":"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2017\/02\/PUBLI-FB-SOLOPTICAL-SAN-VALENTIN-ONLINE-01.jpg","type":"image\/jpeg"}],"twitter_card":"summary","twitter_misc":{"Escrito por":"Mario Andrade","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/soloptical.net\/blog\/#website","url":"https:\/\/soloptical.net\/blog\/","name":"Blog a primera vista","description":"by soloptical","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/soloptical.net\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","@id":"https:\/\/soloptical.net\/blog\/que-regalar-para-san-valentin\/#primaryimage","inLanguage":"es","url":"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2017\/02\/PUBLI-FB-SOLOPTICAL-SAN-VALENTIN-ONLINE-01.jpg","contentUrl":"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2017\/02\/PUBLI-FB-SOLOPTICAL-SAN-VALENTIN-ONLINE-01.jpg","width":2500,"height":1306},{"@type":"WebPage","@id":"https:\/\/soloptical.net\/blog\/que-regalar-para-san-valentin\/#webpage","url":"https:\/\/soloptical.net\/blog\/que-regalar-para-san-valentin\/","name":"\u00bfQu\u00e9 regalar para San Valent\u00edn? - Blog a primera vista","isPartOf":{"@id":"https:\/\/soloptical.net\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/soloptical.net\/blog\/que-regalar-para-san-valentin\/#primaryimage"},"datePublished":"2017-02-10T17:04:12+00:00","dateModified":"2017-09-27T10:23:09+00:00","author":{"@id":"https:\/\/soloptical.net\/blog\/#\/schema\/person\/ff9996614428adaccc3f660afa419f7c"},"description":"S\u00f3lo quedan d\u00edas para San Valent\u00edn \u00a1Os traemos varias ideas para que sepas qu\u00e9 regalar para san Valentin y pases un gran d\u00eda!\u00a1Entra y desc\u00fabrelo!","breadcrumb":{"@id":"https:\/\/soloptical.net\/blog\/que-regalar-para-san-valentin\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/soloptical.net\/blog\/que-regalar-para-san-valentin\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/soloptical.net\/blog\/que-regalar-para-san-valentin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/soloptical.net\/blog\/"},{"@type":"ListItem","position":2,"name":"\u00bfQu\u00e9 regalar para San Valent\u00edn?"}]},{"@type":"Person","@id":"https:\/\/soloptical.net\/blog\/#\/schema\/person\/ff9996614428adaccc3f660afa419f7c","name":"Mario Andrade","image":{"@type":"ImageObject","@id":"https:\/\/soloptical.net\/blog\/#personlogo","inLanguage":"es","url":"https:\/\/secure.gravatar.com\/avatar\/bd6aca70d99c4eb6eb996fb36630b1d3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bd6aca70d99c4eb6eb996fb36630b1d3?s=96&d=mm&r=g","caption":"Mario Andrade"},"sameAs":["http:\/\/www.soloptical.com"],"url":"https:\/\/soloptical.net\/blog\/author\/mario\/"}]}},"_links":{"self":[{"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/posts\/4472"}],"collection":[{"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/comments?post=4472"}],"version-history":[{"count":5,"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/posts\/4472\/revisions"}],"predecessor-version":[{"id":4651,"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/posts\/4472\/revisions\/4651"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/media\/4475"}],"wp:attachment":[{"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/media?parent=4472"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/categories?post=4472"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/tags?post=4472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}