{"id":4627,"date":"2017-06-18T10:00:28","date_gmt":"2017-06-18T08:00:28","guid":{"rendered":"http:\/\/blog.soloptical.net\/?p=4627"},"modified":"2017-09-27T11:44:25","modified_gmt":"2017-09-27T09:44:25","slug":"5-consejos-veraniegos-para-tus-oidos","status":"publish","type":"post","link":"https:\/\/soloptical.net\/blog\/5-consejos-veraniegos-para-tus-oidos\/","title":{"rendered":"5 Consejos veraniegos para tus o\u00eddos"},"content":{"rendered":"<p>S\u00f3lo quedan unos d\u00edas para que d\u00e9 comienzo el verano oficialmente y comiencen las largas tardes de piscina y playa para todos.<\/p>\n<p>En Soloptical somos m\u00e1s que \u00f3pticos. Adem\u00e1s de nuestros centros \u00f3pticos contamos con gabinetes audiol\u00f3gicos en la mayor\u00eda de nuestras tiendas y es por eso por lo que el post de hoy lo dedicaremos a daros varios consejos para cuidar vuestros o\u00eddos durante estos meses.<\/p>\n<h2>1\u00ba Imprescindible secar nuestros o\u00eddos tras cada ba\u00f1o<\/h2>\n<p>La humedad provocada por el contacto del agua provoca que se puedan crear otitis o diferentes molestias en el o\u00eddo por lo que es aconsejable que cada vez que salgamos del agua nos sequemos los o\u00eddos.<\/p>\n<h2>2\u00ba Tener especial cuidado con la limpieza de nuestros o\u00eddos:<\/h2>\n<p>Otro consejo muy importante es prestar mucha m\u00e1s atenci\u00f3n la higiene de nuestros o\u00eddos de la que le prestamos el resto del a\u00f1o. Con el agua la cera que tenemos acumulada puede absorber el agua, hincharse y provocar tapones.<\/p>\n<p>En ese caso es aconsejable acudir al especialista los primeros d\u00edas del verano y que nos aconseje c\u00f3mo hacer una limpieza adecuada o que sea \u00e9l el que la realice. Es importante recordar que si hacemos uso de los bastoncillos sea con especial atenci\u00f3n ya que si no los usamos de manera correcta corremos riesgo de empujar la cera y provocar una infecci\u00f3n.<\/p>\n<h2>3\u00ba \u00a1Cuidado con las zambullidas!<\/h2>\n<p>Aunque una zambullida normal en la piscina o en la playa no suele provocar ning\u00fan incidente, hay que tener cuidado cuando las realizamos desde grandes alturas o a una gran velocidad ya que puede da\u00f1ar la membrana del t\u00edmpano.<\/p>\n<p>Es recomendable que las personas con problemas de o\u00eddo como fuertes dolores o constantes otitis, se abstengan de realizar este tipo de actividades y as\u00ed evitar que empeore.<\/p>\n<h2>4\u00ba Si practicas deportes acu\u00e1ticos usa tapones<\/h2>\n<p>Si vais a practicar un deporte acu\u00e1tico lo m\u00e1s adecuado es contar con protectores auditivos, preferiblemente los fabricados de silicona hipoal\u00e9rgica, que se ajustan a la forma de nuestro canal auditivo, o los hechos a medida.<\/p>\n<h2>5\u00ba Si sois propensos a sufrir problemas de o\u00eddo usa tapones a medida:<\/h2>\n<p>Es conveniente hacer uso de protectores auditivos fabricados a medida ya que disminuye el nivel de humedad provocado por el contacto del agua.<\/p>\n<p>Durante<strong> todo el verano en Soloptical<\/strong> podr\u00e1s beneficiarte de nuestra promoci\u00f3n de 59\u20ac el <strong>par de tapones de ba\u00f1o adem\u00e1s de una revisi\u00f3n audiol\u00f3gica GRATIS<\/strong><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/bit.ly\/opticassoloptical\" title=\"VISITA NUESTRAS TIENDAS\" class=\"btn btn-primary btn-normal btn-inline \" target=\"_blank\"><i class=\"\"><\/i> VISITA NUESTRAS TIENDAS<\/a><!-- .btn -->\n","protected":false},"excerpt":{"rendered":"<p>S\u00f3lo quedan unos d\u00edas para que d\u00e9 comienzo el verano oficialmente y comiencen las largas tardes de piscina y playa para todos. En Soloptical somos m\u00e1s que \u00f3pticos. Adem\u00e1s de nuestros centros \u00f3pticos contamos con gabinetes audiol\u00f3gicos en la mayor\u00eda de nuestras tiendas y es por eso por lo que el post de hoy lo&nbsp;<a href=\"https:\/\/soloptical.net\/blog\/5-consejos-veraniegos-para-tus-oidos\/\" class=\"read-more\">Continua leyendo<\/a><\/p>\n","protected":false},"author":10,"featured_media":4628,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[299,253,251,116],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>5 Consejos veraniegos para tus o\u00eddos - Soloptical<\/title>\n<meta name=\"description\" content=\"Llega el verano y las posibles otitis. \u00a1Te damos 5 consejos veraniegos para tus o\u00eddos imprescindibles para disfrutar del verano al 100%!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/soloptical.net\/blog\/5-consejos-veraniegos-para-tus-oidos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"5 Consejos veraniegos para tus o\u00eddos - Soloptical\" \/>\n<meta property=\"og:description\" content=\"Llega el verano y las posibles otitis. \u00a1Te damos 5 consejos veraniegos para tus o\u00eddos imprescindibles para disfrutar del verano al 100%!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/soloptical.net\/blog\/5-consejos-veraniegos-para-tus-oidos\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog a primera vista\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-18T08:00:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-09-27T09:44:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2017\/06\/consejos-auditivos-blog.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mario Andrade\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/soloptical.net\/blog\/#website\",\"url\":\"https:\/\/soloptical.net\/blog\/\",\"name\":\"Blog a primera vista\",\"description\":\"by soloptical\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/soloptical.net\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/soloptical.net\/blog\/5-consejos-veraniegos-para-tus-oidos\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2017\/06\/consejos-auditivos-blog.jpg\",\"contentUrl\":\"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2017\/06\/consejos-auditivos-blog.jpg\",\"width\":800,\"height\":600},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/soloptical.net\/blog\/5-consejos-veraniegos-para-tus-oidos\/#webpage\",\"url\":\"https:\/\/soloptical.net\/blog\/5-consejos-veraniegos-para-tus-oidos\/\",\"name\":\"5 Consejos veraniegos para tus o\u00eddos - Soloptical\",\"isPartOf\":{\"@id\":\"https:\/\/soloptical.net\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/soloptical.net\/blog\/5-consejos-veraniegos-para-tus-oidos\/#primaryimage\"},\"datePublished\":\"2017-06-18T08:00:28+00:00\",\"dateModified\":\"2017-09-27T09:44:25+00:00\",\"author\":{\"@id\":\"https:\/\/soloptical.net\/blog\/#\/schema\/person\/ff9996614428adaccc3f660afa419f7c\"},\"description\":\"Llega el verano y las posibles otitis. \u00a1Te damos 5 consejos veraniegos para tus o\u00eddos imprescindibles para disfrutar del verano al 100%!\",\"breadcrumb\":{\"@id\":\"https:\/\/soloptical.net\/blog\/5-consejos-veraniegos-para-tus-oidos\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/soloptical.net\/blog\/5-consejos-veraniegos-para-tus-oidos\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/soloptical.net\/blog\/5-consejos-veraniegos-para-tus-oidos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/soloptical.net\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"5 Consejos veraniegos para tus o\u00eddos\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/soloptical.net\/blog\/#\/schema\/person\/ff9996614428adaccc3f660afa419f7c\",\"name\":\"Mario Andrade\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/soloptical.net\/blog\/#personlogo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/bd6aca70d99c4eb6eb996fb36630b1d3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/bd6aca70d99c4eb6eb996fb36630b1d3?s=96&d=mm&r=g\",\"caption\":\"Mario Andrade\"},\"sameAs\":[\"http:\/\/www.soloptical.com\"],\"url\":\"https:\/\/soloptical.net\/blog\/author\/mario\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"5 Consejos veraniegos para tus o\u00eddos - Soloptical","description":"Llega el verano y las posibles otitis. \u00a1Te damos 5 consejos veraniegos para tus o\u00eddos imprescindibles para disfrutar del verano al 100%!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/soloptical.net\/blog\/5-consejos-veraniegos-para-tus-oidos\/","og_locale":"es_ES","og_type":"article","og_title":"5 Consejos veraniegos para tus o\u00eddos - Soloptical","og_description":"Llega el verano y las posibles otitis. \u00a1Te damos 5 consejos veraniegos para tus o\u00eddos imprescindibles para disfrutar del verano al 100%!","og_url":"https:\/\/soloptical.net\/blog\/5-consejos-veraniegos-para-tus-oidos\/","og_site_name":"Blog a primera vista","article_published_time":"2017-06-18T08:00:28+00:00","article_modified_time":"2017-09-27T09:44:25+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2017\/06\/consejos-auditivos-blog.jpg","type":"image\/jpeg"}],"twitter_card":"summary","twitter_misc":{"Escrito por":"Mario Andrade","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/soloptical.net\/blog\/#website","url":"https:\/\/soloptical.net\/blog\/","name":"Blog a primera vista","description":"by soloptical","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/soloptical.net\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","@id":"https:\/\/soloptical.net\/blog\/5-consejos-veraniegos-para-tus-oidos\/#primaryimage","inLanguage":"es","url":"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2017\/06\/consejos-auditivos-blog.jpg","contentUrl":"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2017\/06\/consejos-auditivos-blog.jpg","width":800,"height":600},{"@type":"WebPage","@id":"https:\/\/soloptical.net\/blog\/5-consejos-veraniegos-para-tus-oidos\/#webpage","url":"https:\/\/soloptical.net\/blog\/5-consejos-veraniegos-para-tus-oidos\/","name":"5 Consejos veraniegos para tus o\u00eddos - Soloptical","isPartOf":{"@id":"https:\/\/soloptical.net\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/soloptical.net\/blog\/5-consejos-veraniegos-para-tus-oidos\/#primaryimage"},"datePublished":"2017-06-18T08:00:28+00:00","dateModified":"2017-09-27T09:44:25+00:00","author":{"@id":"https:\/\/soloptical.net\/blog\/#\/schema\/person\/ff9996614428adaccc3f660afa419f7c"},"description":"Llega el verano y las posibles otitis. \u00a1Te damos 5 consejos veraniegos para tus o\u00eddos imprescindibles para disfrutar del verano al 100%!","breadcrumb":{"@id":"https:\/\/soloptical.net\/blog\/5-consejos-veraniegos-para-tus-oidos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/soloptical.net\/blog\/5-consejos-veraniegos-para-tus-oidos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/soloptical.net\/blog\/5-consejos-veraniegos-para-tus-oidos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/soloptical.net\/blog\/"},{"@type":"ListItem","position":2,"name":"5 Consejos veraniegos para tus o\u00eddos"}]},{"@type":"Person","@id":"https:\/\/soloptical.net\/blog\/#\/schema\/person\/ff9996614428adaccc3f660afa419f7c","name":"Mario Andrade","image":{"@type":"ImageObject","@id":"https:\/\/soloptical.net\/blog\/#personlogo","inLanguage":"es","url":"https:\/\/secure.gravatar.com\/avatar\/bd6aca70d99c4eb6eb996fb36630b1d3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bd6aca70d99c4eb6eb996fb36630b1d3?s=96&d=mm&r=g","caption":"Mario Andrade"},"sameAs":["http:\/\/www.soloptical.com"],"url":"https:\/\/soloptical.net\/blog\/author\/mario\/"}]}},"_links":{"self":[{"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/posts\/4627"}],"collection":[{"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/comments?post=4627"}],"version-history":[{"count":5,"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/posts\/4627\/revisions"}],"predecessor-version":[{"id":4633,"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/posts\/4627\/revisions\/4633"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/media\/4628"}],"wp:attachment":[{"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/media?parent=4627"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/categories?post=4627"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/tags?post=4627"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}