{"id":4730,"date":"2017-10-18T10:56:49","date_gmt":"2017-10-18T08:56:49","guid":{"rendered":"http:\/\/blog.soloptical.net\/?p=4730"},"modified":"2017-10-18T10:56:49","modified_gmt":"2017-10-18T08:56:49","slug":"serieadictos-iii","status":"publish","type":"post","link":"https:\/\/soloptical.net\/blog\/serieadictos-iii\/","title":{"rendered":"SERIEADICTOS III"},"content":{"rendered":"<p>Como serieadictos y amantes de las gafas, volvemos con el repaso de las monturas y sunnnies m\u00e1s llamativas y recordadas de las series de los \u00faltimos a\u00f1os. Elementos de moda que van m\u00e1s all\u00e1 del vestuario, dando car\u00e1cter a los personajes e incluso convirti\u00e9ndose en piezas ic\u00f3nicas.<\/p>\n<h3><strong>EL FUTURO SALVAJE OESTE<\/strong><\/h3>\n<p><strong>Westworld<\/strong> es una de las series de ciencia ficci\u00f3n con m\u00e1s seguidores, pese a s\u00f3lo haber tenido en emisi\u00f3n hasta la fecha una \u00fanica temporada. Se trata de una remake realmente cuidado e innovador de una casi olvidada pel\u00edcula de los 70.<\/p>\n<p>Con una interpretaci\u00f3n impecable de un reparto encabezado por el incombustible Anthony Hopkins, hoy nos quedamos con el personaje de <em>Bernard<\/em>, clave para entender el complejo mundo futurista de <strong>Westworld<\/strong>.<\/p>\n<p><a href=\"http:\/\/blog.soloptical.net\/wp-content\/uploads\/2017\/10\/00_soloptical_westworld.jpg\"><img loading=\"lazy\" class=\"alignnone size-full wp-image-4735\" src=\"http:\/\/blog.soloptical.net\/wp-content\/uploads\/2017\/10\/00_soloptical_westworld.jpg\" alt=\"Serieadictos. Gafas en Westworld.\" width=\"597\" height=\"396\" srcset=\"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2017\/10\/00_soloptical_westworld.jpg 597w, https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2017\/10\/00_soloptical_westworld-300x200.jpg 300w, https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2017\/10\/00_soloptical_westworld-573x380.jpg 573w\" sizes=\"(max-width: 597px) 100vw, 597px\" \/><\/a><\/p>\n<p>Sus gafas siempre un poco bajas son el elemento m\u00e1s caracter\u00edstico de este especialista en rob\u00f3tica, que le confieren ese aire de distra\u00edda concentraci\u00f3n y mirada algo melanc\u00f3lica.<\/p>\n<p>La elegante simplicidad de modelos como las monturas de <a href=\"https:\/\/www.soloptical.net\/ofertas\/\" target=\"_blank\">RAYBAN o EMPORIO\u00a0<\/a>\u00a0de nuestro Magazine\u00a0evocan las gafas del personaje, con un estilo que nunca pasa de moda.<\/p>\n<h3><strong>SER FRIKI SE LLEVA<\/strong><\/h3>\n<p><a href=\"http:\/\/blog.soloptical.net\/wp-content\/uploads\/2017\/10\/00_soloptical_thebigbang.jpg\"><img loading=\"lazy\" class=\"alignnone size-full wp-image-4737\" src=\"http:\/\/blog.soloptical.net\/wp-content\/uploads\/2017\/10\/00_soloptical_thebigbang.jpg\" alt=\"Serieadictos. Gafas en The Big Bang Theory\" width=\"597\" height=\"396\" srcset=\"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2017\/10\/00_soloptical_thebigbang.jpg 597w, https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2017\/10\/00_soloptical_thebigbang-300x200.jpg 300w, https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2017\/10\/00_soloptical_thebigbang-573x380.jpg 573w\" sizes=\"(max-width: 597px) 100vw, 597px\" \/><\/a><\/p>\n<p>Tras m\u00e1s de una d\u00e9cada en antena, y gracias a un humor desenfadado y el merchandising m\u00e1s amplio del mercado, <strong>The Big Bang Theory<\/strong> ha reinventado las sitcom poniendo de moda lo friki.<\/p>\n<p>Este grupo de amigos cient\u00edficos amantes de los comics y la ciencia ficci\u00f3n, empezaron como veintea\u00f1eros y ya cuentan con treinta y tantos, pero han mantenido pr\u00e1cticamente intacta su est\u00e9tica.<\/p>\n<p>Inamovible, como su \u00e9xito televisivo, han sido omipresentes en todas las temporadas las gafas de <em>Leonard<\/em>. Un icono de <a href=\"https:\/\/www.soloptical.net\/product-category\/ray-ban-es-es-gafas-graduadas\/\" target=\"_blank\">RAYBAN<\/a>, convertido en icono unisex global de la cultura nerd.<\/p>\n<p>Aunque con la incorporaci\u00f3n de personajes como <em>Bernadette<\/em> o <em>Amy<\/em> podemos ver ese estilo de gafa pero en un corte m\u00e1s femenino en modelos similares a los de SXT o RALPH y TOMMY disponibles en nuestras<a href=\"https:\/\/www.soloptical.net\/ofertas\/\" target=\"_blank\"> ofertas de oto\u00f1o<\/a>.<\/p>\n<h3><strong>LOS HERMANOS M\u00c1S DUROS<\/strong><\/h3>\n<p>Si hablamos de <em>Michael Scofield<\/em> y <em>Lincoln Burrows<\/em>, muy pocos no reconocer\u00e1n en esos nombres a los hermanos encargados de hacernos vibrar con su plan de escape carcelario y el acoso al que se ven sometido como fugitivos.<\/p>\n<p><strong>Prison Break<\/strong> ha sido una serie de \u00e9xito, recientemente ampliada con una secuela, con una trama adictiva que saca partido a la combinaci\u00f3n de inteligencia y rudeza de los dos hermanos.<\/p>\n<p><a href=\"http:\/\/blog.soloptical.net\/wp-content\/uploads\/2017\/10\/00_soloptical_prisionbreak.jpg\"><img loading=\"lazy\" class=\"alignnone size-full wp-image-4738\" src=\"http:\/\/blog.soloptical.net\/wp-content\/uploads\/2017\/10\/00_soloptical_prisionbreak.jpg\" alt=\"Serieadictos. Gafas en Prision Break\" width=\"597\" height=\"396\" srcset=\"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2017\/10\/00_soloptical_prisionbreak.jpg 597w, https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2017\/10\/00_soloptical_prisionbreak-300x200.jpg 300w, https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2017\/10\/00_soloptical_prisionbreak-573x380.jpg 573w\" sizes=\"(max-width: 597px) 100vw, 597px\" \/><\/a><\/p>\n<p>Con una est\u00e9tica cargada de tipos duros y testosterona no pod\u00edan faltar las m\u00edticas <a href=\"https:\/\/soloptical.net\/online\/21-rayban#\/estilo-aviador\" target=\"_blank\">AVIATOR <\/a>acompa\u00f1ando a los protagonistas en su eterna huida. Y si te gusta el estilo de <em>Lincoln<\/em>, pero con un toque m\u00e1s moderno, te recomendamos estas <a href=\"https:\/\/soloptical.net\/online\/carrera-hombre\/296-carrera-newchampion-762753291813.html\" target=\"_blank\">CARRERA<\/a>, 100%actitud.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como serieadictos y amantes de las gafas, volvemos con el repaso de las monturas y sunnnies m\u00e1s llamativas y recordadas de las series de los \u00faltimos a\u00f1os. Elementos de moda que van m\u00e1s all\u00e1 del vestuario, dando car\u00e1cter a los personajes e incluso convirti\u00e9ndose en piezas ic\u00f3nicas. EL FUTURO SALVAJE OESTE Westworld es una de&nbsp;<a href=\"https:\/\/soloptical.net\/blog\/serieadictos-iii\/\" class=\"read-more\">Continua leyendo<\/a><\/p>\n","protected":false},"author":10,"featured_media":4733,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[30,265,2,4],"tags":[316,51,102,268,48,305,74,314,52,315],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>SERIEADICTOS III - Blog a primera vista<\/title>\n<meta name=\"description\" content=\"Somos serieadictos y amantes de las gafas. Descubre ahora cu\u00e1les son las gafas que usan tus personajes favoritos de Big Bang, Prision Break o Westworld.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/soloptical.net\/blog\/serieadictos-iii\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SERIEADICTOS III - Blog a primera vista\" \/>\n<meta property=\"og:description\" content=\"Somos serieadictos y amantes de las gafas. Descubre ahora cu\u00e1les son las gafas que usan tus personajes favoritos de Big Bang, Prision Break o Westworld.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/soloptical.net\/blog\/serieadictos-iii\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog a primera vista\" \/>\n<meta property=\"article:published_time\" content=\"2017-10-18T08:56:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2017\/10\/00_ADICTOSSERIES3_post.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"597\" \/>\n\t<meta property=\"og:image:height\" content=\"378\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mario Andrade\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/soloptical.net\/blog\/#website\",\"url\":\"https:\/\/soloptical.net\/blog\/\",\"name\":\"Blog a primera vista\",\"description\":\"by soloptical\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/soloptical.net\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/soloptical.net\/blog\/serieadictos-iii\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2017\/10\/00_ADICTOSSERIES3_post.jpg\",\"contentUrl\":\"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2017\/10\/00_ADICTOSSERIES3_post.jpg\",\"width\":597,\"height\":378,\"caption\":\"Serieadictos. Big Bang, Westworld, Prision Break.\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/soloptical.net\/blog\/serieadictos-iii\/#webpage\",\"url\":\"https:\/\/soloptical.net\/blog\/serieadictos-iii\/\",\"name\":\"SERIEADICTOS III - Blog a primera vista\",\"isPartOf\":{\"@id\":\"https:\/\/soloptical.net\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/soloptical.net\/blog\/serieadictos-iii\/#primaryimage\"},\"datePublished\":\"2017-10-18T08:56:49+00:00\",\"dateModified\":\"2017-10-18T08:56:49+00:00\",\"author\":{\"@id\":\"https:\/\/soloptical.net\/blog\/#\/schema\/person\/ff9996614428adaccc3f660afa419f7c\"},\"description\":\"Somos serieadictos y amantes de las gafas. Descubre ahora cu\u00e1les son las gafas que usan tus personajes favoritos de Big Bang, Prision Break o Westworld.\",\"breadcrumb\":{\"@id\":\"https:\/\/soloptical.net\/blog\/serieadictos-iii\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/soloptical.net\/blog\/serieadictos-iii\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/soloptical.net\/blog\/serieadictos-iii\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/soloptical.net\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SERIEADICTOS III\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/soloptical.net\/blog\/#\/schema\/person\/ff9996614428adaccc3f660afa419f7c\",\"name\":\"Mario Andrade\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/soloptical.net\/blog\/#personlogo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/bd6aca70d99c4eb6eb996fb36630b1d3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/bd6aca70d99c4eb6eb996fb36630b1d3?s=96&d=mm&r=g\",\"caption\":\"Mario Andrade\"},\"sameAs\":[\"http:\/\/www.soloptical.com\"],\"url\":\"https:\/\/soloptical.net\/blog\/author\/mario\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SERIEADICTOS III - Blog a primera vista","description":"Somos serieadictos y amantes de las gafas. Descubre ahora cu\u00e1les son las gafas que usan tus personajes favoritos de Big Bang, Prision Break o Westworld.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/soloptical.net\/blog\/serieadictos-iii\/","og_locale":"es_ES","og_type":"article","og_title":"SERIEADICTOS III - Blog a primera vista","og_description":"Somos serieadictos y amantes de las gafas. Descubre ahora cu\u00e1les son las gafas que usan tus personajes favoritos de Big Bang, Prision Break o Westworld.","og_url":"https:\/\/soloptical.net\/blog\/serieadictos-iii\/","og_site_name":"Blog a primera vista","article_published_time":"2017-10-18T08:56:49+00:00","og_image":[{"width":597,"height":378,"url":"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2017\/10\/00_ADICTOSSERIES3_post.jpg","type":"image\/jpeg"}],"twitter_card":"summary","twitter_misc":{"Escrito por":"Mario Andrade","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/soloptical.net\/blog\/#website","url":"https:\/\/soloptical.net\/blog\/","name":"Blog a primera vista","description":"by soloptical","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/soloptical.net\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","@id":"https:\/\/soloptical.net\/blog\/serieadictos-iii\/#primaryimage","inLanguage":"es","url":"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2017\/10\/00_ADICTOSSERIES3_post.jpg","contentUrl":"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2017\/10\/00_ADICTOSSERIES3_post.jpg","width":597,"height":378,"caption":"Serieadictos. Big Bang, Westworld, Prision Break."},{"@type":"WebPage","@id":"https:\/\/soloptical.net\/blog\/serieadictos-iii\/#webpage","url":"https:\/\/soloptical.net\/blog\/serieadictos-iii\/","name":"SERIEADICTOS III - Blog a primera vista","isPartOf":{"@id":"https:\/\/soloptical.net\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/soloptical.net\/blog\/serieadictos-iii\/#primaryimage"},"datePublished":"2017-10-18T08:56:49+00:00","dateModified":"2017-10-18T08:56:49+00:00","author":{"@id":"https:\/\/soloptical.net\/blog\/#\/schema\/person\/ff9996614428adaccc3f660afa419f7c"},"description":"Somos serieadictos y amantes de las gafas. Descubre ahora cu\u00e1les son las gafas que usan tus personajes favoritos de Big Bang, Prision Break o Westworld.","breadcrumb":{"@id":"https:\/\/soloptical.net\/blog\/serieadictos-iii\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/soloptical.net\/blog\/serieadictos-iii\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/soloptical.net\/blog\/serieadictos-iii\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/soloptical.net\/blog\/"},{"@type":"ListItem","position":2,"name":"SERIEADICTOS III"}]},{"@type":"Person","@id":"https:\/\/soloptical.net\/blog\/#\/schema\/person\/ff9996614428adaccc3f660afa419f7c","name":"Mario Andrade","image":{"@type":"ImageObject","@id":"https:\/\/soloptical.net\/blog\/#personlogo","inLanguage":"es","url":"https:\/\/secure.gravatar.com\/avatar\/bd6aca70d99c4eb6eb996fb36630b1d3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bd6aca70d99c4eb6eb996fb36630b1d3?s=96&d=mm&r=g","caption":"Mario Andrade"},"sameAs":["http:\/\/www.soloptical.com"],"url":"https:\/\/soloptical.net\/blog\/author\/mario\/"}]}},"_links":{"self":[{"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/posts\/4730"}],"collection":[{"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/comments?post=4730"}],"version-history":[{"count":6,"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/posts\/4730\/revisions"}],"predecessor-version":[{"id":4879,"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/posts\/4730\/revisions\/4879"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/media\/4733"}],"wp:attachment":[{"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/media?parent=4730"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/categories?post=4730"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/tags?post=4730"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}