{"id":5420,"date":"2019-06-12T17:41:49","date_gmt":"2019-06-12T15:41:49","guid":{"rendered":"http:\/\/blog.soloptical.net\/?p=5420"},"modified":"2019-06-25T15:39:26","modified_gmt":"2019-06-25T13:39:26","slug":"tapones-para-bano","status":"publish","type":"post","link":"https:\/\/soloptical.net\/blog\/tapones-para-bano\/","title":{"rendered":"Tapones para ba\u00f1o"},"content":{"rendered":"<p>Llega el tiempo de chapuzones y tambi\u00e9n de <strong>otitis externa<\/strong> para las personas con predisposici\u00f3n a los problemas de o\u00eddo. Con unos <strong>tapones para ba\u00f1o<\/strong>\u00a0para ni\u00f1os y adultos disfrutar\u00e1n m\u00e1s de la playa y la piscina&#8230;<\/p>\n<p><a href=\"http:\/\/blog.soloptical.net\/wp-content\/uploads\/2019\/06\/Dise\u00f1o-sin-t\u00edtulo-56.png\"><img loading=\"lazy\" class=\"size-full wp-image-5422 aligncenter\" src=\"http:\/\/blog.soloptical.net\/wp-content\/uploads\/2019\/06\/Dise\u00f1o-sin-t\u00edtulo-56.png\" alt=\"ni\u00f1a con tapones de ba\u00f1o\" width=\"940\" height=\"788\" srcset=\"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2019\/06\/Dise\u00f1o-sin-t\u00edtulo-56.png 940w, https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2019\/06\/Dise\u00f1o-sin-t\u00edtulo-56-300x251.png 300w, https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2019\/06\/Dise\u00f1o-sin-t\u00edtulo-56-877x735.png 877w, https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2019\/06\/Dise\u00f1o-sin-t\u00edtulo-56-513x430.png 513w\" sizes=\"(max-width: 940px) 100vw, 940px\" \/><\/a><\/p>\n<p>Toalla, ba\u00f1ador y gafas de sol. Ya sea en la piscina o en la playa,\u00a0 refrescarse con un buen chapuz\u00f3n es lo suyo cuando el term\u00f3metro se pone caliente. Esa refrescante sensaci\u00f3n, agradable para la mayor\u00eda de personas, se convierte en una actividad de riesgo para un reducido porcentaje de la poblaci\u00f3n, quienes padecen drenajes, perforaciones de t\u00edmpano y son\u00a0 propensos a contraer dolorosas otitis, inflamaciones e infecciones de o\u00eddo.Da igual que el agua sea dulce o salada , lo mejor es prevenir esta amenaza con unos <a href=\"https:\/\/www.soloptical.net\/audiologia\/accesorios-e-higiene-auditiva\/\" target=\"_blank\">tapones<\/a> para nadar y refrescarse con tranquilidad desde la m\u00e1s tierna infancia.<\/p>\n<p><img loading=\"lazy\" class=\" size-large wp-image-5423 aligncenter\" src=\"http:\/\/blog.soloptical.net\/wp-content\/uploads\/2019\/06\/taponesdeba\u00f1o-1024x768.jpg\" alt=\"tapones de ba\u00f1o\" width=\"900\" height=\"675\" srcset=\"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2019\/06\/taponesdeba\u00f1o-1024x768.jpg 1024w, https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2019\/06\/taponesdeba\u00f1o-300x225.jpg 300w, https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2019\/06\/taponesdeba\u00f1o-980x735.jpg 980w, https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2019\/06\/taponesdeba\u00f1o-700x525.jpg 700w, https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2019\/06\/taponesdeba\u00f1o-573x430.jpg 573w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/p>\n<h3><strong>Tapones para unos o\u00eddos m\u00e1s sanos<\/strong><\/h3>\n<p>En el departamento de <a href=\"https:\/\/www.soloptical.net\/audiologia\/accesorios-e-higiene-auditiva\/\" target=\"_blank\">audiolog\u00eda<\/a> de Soloptical s\u00f3lo comercializamos y te proporcionamos los <a href=\"https:\/\/www.soloptical.net\/audiologia\/accesorios-e-higiene-auditiva\/\" target=\"_blank\">tapones de ba\u00f1o<\/a> de \u00faltima generaci\u00f3n realizados a medida. Solicitas cita en el departamento de audiolog\u00eda de tu \u00f3ptica Soloptical m\u00e1s cercana, nuestro audioprotesista toma\u00a0 un molde a escala natural de tus canales auditivos y de esta forma fabricamos unos tapones en silicona de alta resistencia e impermeabilidad garantizada. Con tus nuevos tapones sellas tus o\u00eddos y ya te puedes ba\u00f1ar con m\u00e1s tranquilidad a salvo de inflamaciones, infecciones y hongos.<\/p>\n<p><img loading=\"lazy\" class=\" size-large wp-image-5424 aligncenter\" src=\"http:\/\/blog.soloptical.net\/wp-content\/uploads\/2019\/06\/tapones-de-ba\u00f1o-para-nataci\u00f3n-1024x686.jpg\" alt=\"tapones de\" width=\"900\" height=\"603\" srcset=\"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2019\/06\/tapones-de-ba\u00f1o-para-nataci\u00f3n-1024x686.jpg 1024w, https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2019\/06\/tapones-de-ba\u00f1o-para-nataci\u00f3n-300x200.jpg 300w, https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2019\/06\/tapones-de-ba\u00f1o-para-nataci\u00f3n-980x656.jpg 980w, https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2019\/06\/tapones-de-ba\u00f1o-para-nataci\u00f3n-573x384.jpg 573w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/p>\n<p><a href=\"http:\/\/blog.soloptical.net\/wp-content\/uploads\/2019\/06\/tapones-de-ba\u00f1o-soloptical.jpg\"><img loading=\"lazy\" class=\"alignright size-full wp-image-5425\" src=\"http:\/\/blog.soloptical.net\/wp-content\/uploads\/2019\/06\/tapones-de-ba\u00f1o-soloptical.jpg\" alt=\"tapones de ba\u00f1o soloptical\" width=\"567\" height=\"202\" srcset=\"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2019\/06\/tapones-de-ba\u00f1o-soloptical.jpg 567w, https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2019\/06\/tapones-de-ba\u00f1o-soloptical-300x107.jpg 300w\" sizes=\"(max-width: 567px) 100vw, 567px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h2><a href=\"http:\/\/blog.soloptical.net\/wp-content\/uploads\/2019\/06\/Ba\u00f1o-tapones.jpg\"><br \/>\n<\/a><img loading=\"lazy\" class=\" size-large wp-image-5431 aligncenter\" src=\"http:\/\/blog.soloptical.net\/wp-content\/uploads\/2019\/06\/Ba\u00f1o-tapones-1024x356.jpg\" alt=\"Ba\u00f1o tapones\" width=\"900\" height=\"313\" srcset=\"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2019\/06\/Ba\u00f1o-tapones-1024x356.jpg 1024w, https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2019\/06\/Ba\u00f1o-tapones-300x104.jpg 300w, https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2019\/06\/Ba\u00f1o-tapones-980x340.jpg 980w, https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2019\/06\/Ba\u00f1o-tapones-573x199.jpg 573w, https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2019\/06\/Ba\u00f1o-tapones.jpg 1100w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/h2>\n<h3><strong>Tapones para todos los deportes n\u00e1uticos\u00a0 y todas la edades<\/strong><\/h3>\n<p>Para disfrutar de un verano en acci\u00f3n. Practica con m\u00e1s seguridad tu deporte preferido: submarinismo, nataci\u00f3n, surf, padel surf, kite surf, body surf y remo con unos<a href=\"https:\/\/www.soloptical.net\/audiologia\/accesorios-e-higiene-auditiva\/\" target=\"_blank\"> tapones de ba\u00f1o<\/a>. Los tapones de ba\u00f1o se realizan a medida a partir de los dos a\u00f1os de edad en adelante.<\/p>\n<p><img loading=\"lazy\" class=\" size-large wp-image-5426 aligncenter\" src=\"http:\/\/blog.soloptical.net\/wp-content\/uploads\/2019\/06\/imagen-de-nataci\u00f3n-1024x706.jpg\" alt=\"imagen de nataci\u00f3n\" width=\"900\" height=\"621\" srcset=\"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2019\/06\/imagen-de-nataci\u00f3n-1024x706.jpg 1024w, https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2019\/06\/imagen-de-nataci\u00f3n-300x207.jpg 300w, https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2019\/06\/imagen-de-nataci\u00f3n-980x675.jpg 980w, https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2019\/06\/imagen-de-nataci\u00f3n-573x395.jpg 573w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/p>\n<p>Si tienes los o\u00eddos sensibles o eres proclive a infecciones de o\u00eddo este verano, antes de ir a la piscina o la playa encarga tus tapones en nuestro departamento de <a href=\"https:\/\/www.soloptical.net\/audiologia\/\" target=\"_blank\">audiolog\u00eda<\/a>. De paso puedes aprovechar para probarte\u00a0 la nueva colecci\u00f3n se gafas de sol de \u00faltima moda protecci\u00f3n UV 400 y lentes polarizadas a los precios siempre bajos de <a href=\"https:\/\/www.soloptical.net\/\" target=\"_blank\">Soloptical.<\/a><\/p>\n<p><a href=\"http:\/\/blog.soloptical.net\/wp-content\/uploads\/2019\/06\/deporte.jpg\"><img loading=\"lazy\" class=\"alignright size-large wp-image-5433\" src=\"http:\/\/blog.soloptical.net\/wp-content\/uploads\/2019\/06\/deporte-1024x819.jpg\" alt=\"deporte acuatico\" width=\"900\" height=\"720\" srcset=\"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2019\/06\/deporte-1024x819.jpg 1024w, https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2019\/06\/deporte-300x240.jpg 300w, https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2019\/06\/deporte-919x735.jpg 919w, https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2019\/06\/deporte-538x430.jpg 538w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Llega el tiempo de chapuzones y tambi\u00e9n de otitis externa para las personas con predisposici\u00f3n a los problemas de o\u00eddo. Con unos tapones para ba\u00f1o\u00a0para ni\u00f1os y adultos disfrutar\u00e1n m\u00e1s de la playa y la piscina&#8230; Toalla, ba\u00f1ador y gafas de sol. Ya sea en la piscina o en la playa,\u00a0 refrescarse con un buen&nbsp;<a href=\"https:\/\/soloptical.net\/blog\/tapones-para-bano\/\" class=\"read-more\">Continua leyendo<\/a><\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[299,253,265],"tags":[312,437,438,436,439],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tapones para ba\u00f1o - Blog a primera vista<\/title>\n<meta name=\"description\" content=\"Llega el tiempo de chapuzones y tambi\u00e9n de otitis externa. Con unos tapones para ba\u00f1o para ni\u00f1os y adultos disfrutar\u00e1n m\u00e1s de la playa y la piscina.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/soloptical.net\/blog\/tapones-para-bano\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tapones para ba\u00f1o - Blog a primera vista\" \/>\n<meta property=\"og:description\" content=\"Llega el tiempo de chapuzones y tambi\u00e9n de otitis externa. Con unos tapones para ba\u00f1o para ni\u00f1os y adultos disfrutar\u00e1n m\u00e1s de la playa y la piscina.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/soloptical.net\/blog\/tapones-para-bano\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog a primera vista\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-12T15:41:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-06-25T13:39:26+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/blog.soloptical.net\/wp-content\/uploads\/2019\/06\/Dise\u00f1o-sin-t\u00edtulo-56.png\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mario Andrade\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/soloptical.net\/blog\/#website\",\"url\":\"https:\/\/soloptical.net\/blog\/\",\"name\":\"Blog a primera vista\",\"description\":\"by soloptical\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/soloptical.net\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/soloptical.net\/blog\/tapones-para-bano\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"http:\/\/blog.soloptical.net\/wp-content\/uploads\/2019\/06\/deporte-1024x819.jpg\",\"contentUrl\":\"http:\/\/blog.soloptical.net\/wp-content\/uploads\/2019\/06\/deporte-1024x819.jpg\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/soloptical.net\/blog\/tapones-para-bano\/#webpage\",\"url\":\"https:\/\/soloptical.net\/blog\/tapones-para-bano\/\",\"name\":\"Tapones para ba\u00f1o - Blog a primera vista\",\"isPartOf\":{\"@id\":\"https:\/\/soloptical.net\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/soloptical.net\/blog\/tapones-para-bano\/#primaryimage\"},\"datePublished\":\"2019-06-12T15:41:49+00:00\",\"dateModified\":\"2019-06-25T13:39:26+00:00\",\"author\":{\"@id\":\"https:\/\/soloptical.net\/blog\/#\/schema\/person\/ff9996614428adaccc3f660afa419f7c\"},\"description\":\"Llega el tiempo de chapuzones y tambi\u00e9n de otitis externa. Con unos tapones para ba\u00f1o para ni\u00f1os y adultos disfrutar\u00e1n m\u00e1s de la playa y la piscina.\",\"breadcrumb\":{\"@id\":\"https:\/\/soloptical.net\/blog\/tapones-para-bano\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/soloptical.net\/blog\/tapones-para-bano\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/soloptical.net\/blog\/tapones-para-bano\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/soloptical.net\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tapones para ba\u00f1o\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/soloptical.net\/blog\/#\/schema\/person\/ff9996614428adaccc3f660afa419f7c\",\"name\":\"Mario Andrade\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/soloptical.net\/blog\/#personlogo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/bd6aca70d99c4eb6eb996fb36630b1d3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/bd6aca70d99c4eb6eb996fb36630b1d3?s=96&d=mm&r=g\",\"caption\":\"Mario Andrade\"},\"sameAs\":[\"http:\/\/www.soloptical.com\"],\"url\":\"https:\/\/soloptical.net\/blog\/author\/mario\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tapones para ba\u00f1o - Blog a primera vista","description":"Llega el tiempo de chapuzones y tambi\u00e9n de otitis externa. Con unos tapones para ba\u00f1o para ni\u00f1os y adultos disfrutar\u00e1n m\u00e1s de la playa y la piscina.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/soloptical.net\/blog\/tapones-para-bano\/","og_locale":"es_ES","og_type":"article","og_title":"Tapones para ba\u00f1o - Blog a primera vista","og_description":"Llega el tiempo de chapuzones y tambi\u00e9n de otitis externa. Con unos tapones para ba\u00f1o para ni\u00f1os y adultos disfrutar\u00e1n m\u00e1s de la playa y la piscina.","og_url":"https:\/\/soloptical.net\/blog\/tapones-para-bano\/","og_site_name":"Blog a primera vista","article_published_time":"2019-06-12T15:41:49+00:00","article_modified_time":"2019-06-25T13:39:26+00:00","og_image":[{"url":"http:\/\/blog.soloptical.net\/wp-content\/uploads\/2019\/06\/Dise\u00f1o-sin-t\u00edtulo-56.png"}],"twitter_card":"summary","twitter_misc":{"Escrito por":"Mario Andrade","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/soloptical.net\/blog\/#website","url":"https:\/\/soloptical.net\/blog\/","name":"Blog a primera vista","description":"by soloptical","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/soloptical.net\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","@id":"https:\/\/soloptical.net\/blog\/tapones-para-bano\/#primaryimage","inLanguage":"es","url":"http:\/\/blog.soloptical.net\/wp-content\/uploads\/2019\/06\/deporte-1024x819.jpg","contentUrl":"http:\/\/blog.soloptical.net\/wp-content\/uploads\/2019\/06\/deporte-1024x819.jpg"},{"@type":"WebPage","@id":"https:\/\/soloptical.net\/blog\/tapones-para-bano\/#webpage","url":"https:\/\/soloptical.net\/blog\/tapones-para-bano\/","name":"Tapones para ba\u00f1o - Blog a primera vista","isPartOf":{"@id":"https:\/\/soloptical.net\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/soloptical.net\/blog\/tapones-para-bano\/#primaryimage"},"datePublished":"2019-06-12T15:41:49+00:00","dateModified":"2019-06-25T13:39:26+00:00","author":{"@id":"https:\/\/soloptical.net\/blog\/#\/schema\/person\/ff9996614428adaccc3f660afa419f7c"},"description":"Llega el tiempo de chapuzones y tambi\u00e9n de otitis externa. Con unos tapones para ba\u00f1o para ni\u00f1os y adultos disfrutar\u00e1n m\u00e1s de la playa y la piscina.","breadcrumb":{"@id":"https:\/\/soloptical.net\/blog\/tapones-para-bano\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/soloptical.net\/blog\/tapones-para-bano\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/soloptical.net\/blog\/tapones-para-bano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/soloptical.net\/blog\/"},{"@type":"ListItem","position":2,"name":"Tapones para ba\u00f1o"}]},{"@type":"Person","@id":"https:\/\/soloptical.net\/blog\/#\/schema\/person\/ff9996614428adaccc3f660afa419f7c","name":"Mario Andrade","image":{"@type":"ImageObject","@id":"https:\/\/soloptical.net\/blog\/#personlogo","inLanguage":"es","url":"https:\/\/secure.gravatar.com\/avatar\/bd6aca70d99c4eb6eb996fb36630b1d3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bd6aca70d99c4eb6eb996fb36630b1d3?s=96&d=mm&r=g","caption":"Mario Andrade"},"sameAs":["http:\/\/www.soloptical.com"],"url":"https:\/\/soloptical.net\/blog\/author\/mario\/"}]}},"_links":{"self":[{"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/posts\/5420"}],"collection":[{"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/comments?post=5420"}],"version-history":[{"count":7,"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/posts\/5420\/revisions"}],"predecessor-version":[{"id":5436,"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/posts\/5420\/revisions\/5436"}],"wp:attachment":[{"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/media?parent=5420"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/categories?post=5420"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/tags?post=5420"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}