{"id":5968,"date":"2020-06-23T09:37:18","date_gmt":"2020-06-23T07:37:18","guid":{"rendered":"https:\/\/soloptical.net\/blog\/?p=5968"},"modified":"2020-07-08T13:56:18","modified_gmt":"2020-07-08T11:56:18","slug":"verano-y-lentes-de-contacto","status":"publish","type":"post","link":"https:\/\/soloptical.net\/blog\/verano-y-lentes-de-contacto\/","title":{"rendered":"Verano c\u00f3modo con lentes de contacto"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2018\/12\/Lentillas-ojo-1024x683.jpeg\" alt=\"\" class=\"wp-image-5077\" srcset=\"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2018\/12\/Lentillas-ojo-1024x683.jpeg 1024w, https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2018\/12\/Lentillas-ojo-300x200.jpeg 300w, https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2018\/12\/Lentillas-ojo-980x653.jpeg 980w, https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2018\/12\/Lentillas-ojo-573x382.jpeg 573w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Llegan los d\u00edas de ba\u00f1ador. El verano es para disfrutar y dar alegr\u00eda al cuerpo sin perder de vista los cuidados elementales. Si eres usuari@ de lentes de contacto toma nota de estos consejos. Las lentes de contacto y el verano se llevan muy bien &nbsp;te permiten lucir los \u00faltimos dise\u00f1os gafas de sol.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2020\/06\/selective-focus-side-view-photo-of-a-woman-with-her-eyes-3764499-1024x683.jpg\" alt=\"\" class=\"wp-image-5969\" srcset=\"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2020\/06\/selective-focus-side-view-photo-of-a-woman-with-her-eyes-3764499-1024x683.jpg 1024w, https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2020\/06\/selective-focus-side-view-photo-of-a-woman-with-her-eyes-3764499-300x200.jpg 300w, https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2020\/06\/selective-focus-side-view-photo-of-a-woman-with-her-eyes-3764499-768x513.jpg 768w, https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2020\/06\/selective-focus-side-view-photo-of-a-woman-with-her-eyes-3764499-980x654.jpg 980w, https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2020\/06\/selective-focus-side-view-photo-of-a-woman-with-her-eyes-3764499-573x382.jpg 573w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2>Nada de nadar con lentillas.<\/h2>\n\n\n\n<p>Ni en la piscina, ni en el mar&#8230;<strong>Tus lentillas son muy sensible<\/strong>s y debes de evitar que se contaminen incluso en el jacuzzi o la ducha. Con estas temperaturas m\u00e1s vale prevenir una infecci\u00f3n bacteriana. <em>Si no te queda m\u00e1s remedio que darte un chapuz\u00f3n con las lentes de contacto puestas&nbsp; usa unas gafas de buceo o nataci\u00f3n que a\u00edslen absolutamente el ojo del agu<\/em>a, as\u00ed prevendr\u00e1s desagradables infecciones oculares. Toma tus precauciones porque las piscinas y r\u00edos con agua sin tratar pueden provocarte una infecci\u00f3n en la c\u00f3rnea. Si te vas a ba\u00f1ar olv\u00eddate de las lentes de contacto. Al primer s\u00edntoma o sensaci\u00f3n de tener un \u00abcuerpo extra\u00f1o\u201c en los ojos, o como arenilla, a la m\u00ednima se\u00f1al de infecci\u00f3n, acude a tu oftalm\u00f3logo, incluso de urgencias &nbsp;para que eval\u00fae tu caso. <strong>M\u00e1s vale ser precavid@<\/strong>, las infecciones oculares son delicadas y pueden provocar p\u00e9rdida de visi\u00f3n. Por eso <strong>si vas a ba\u00f1arte hazlo sin  lentillas<\/strong>.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" width=\"450\" height=\"343\" src=\"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2020\/06\/sollens-1-day-silicone-multifocal_1.jpg\" alt=\"\" class=\"wp-image-5970\" srcset=\"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2020\/06\/sollens-1-day-silicone-multifocal_1.jpg 450w, https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2020\/06\/sollens-1-day-silicone-multifocal_1-300x229.jpg 300w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><\/figure><\/div>\n\n\n\n<h2>Un verano m\u00e1s c\u00f3modo con lentes de contacto diarias<\/h2>\n\n\n\n<p>Son d\u00edas y noches &nbsp;de pasarlo bien\u2026 de trasnochar, si encima tienes unos d\u00edas de vacaciones es normal que quieras relajarte un poco huyendo de la rutina habitual de <a href=\"https:\/\/soloptical.net\/es\/liquidos-de-lentillas.html\">los l\u00edquidos<\/a> imprescindibles. Encima si estas vacaciones  sales<strong> de viaje, puede que te resulte m\u00e1s c\u00f3modo usar<\/strong><a href=\"https:\/\/soloptical.net\/es\/lentillas\/sol-lens-1-day-silicone-multifocal.html\"><strong> lentes de contacto diarias<\/strong><\/a><strong> <\/strong>de usar y renovar. Disfruta de  est\u00e9tica y m\u00e1s espacio en tu nec\u00e9ser y  equipaje.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2020\/06\/SOLOPTICAL-Verano20-1646-1024x683.jpg\" alt=\"\" class=\"wp-image-5971\" srcset=\"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2020\/06\/SOLOPTICAL-Verano20-1646-1024x683.jpg 1024w, https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2020\/06\/SOLOPTICAL-Verano20-1646-300x200.jpg 300w, https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2020\/06\/SOLOPTICAL-Verano20-1646-768x512.jpg 768w, https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2020\/06\/SOLOPTICAL-Verano20-1646-980x654.jpg 980w, https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2020\/06\/SOLOPTICAL-Verano20-1646-573x382.jpg 573w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<blockquote class=\"wp-block-quote\"><p>Si vas de viaje  las lentillas de uso diario ocupan menos espacio en tu equipaje<\/p><p><\/p><\/blockquote>\n\n\n\n<p>Ahora que llega la jornada intensiva, p\u00e1sate por tu \u00f3ptica Soloptical m\u00e1s cercana por las lentes de contacto que m\u00e1s te convienen. D\u00e9jate asesorar por nuestros contact\u00f3logos. Si ya eres usuario con experiencia te recomendamos &nbsp;encargar tus lentes de contacto por internet en<a href=\"https:\/\/soloptical.net\/es\/lentillas.html\"> la tienda  online de Soloptical <\/a>y te las enviamos a domicilio para tu mayor comodidad. El verano es tiempo de disfrutar.<\/p>\n\n\n\n<h2><\/h2>\n","protected":false},"excerpt":{"rendered":"<p>Las lentillas son para el verano. Consejos para que disfrutes de unas vacaciones con mayor comodidad.<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[253,3,283],"tags":[356,271,121,434,72],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Verano c\u00f3modo con lentes de contacto - Blog a primera vista<\/title>\n<meta name=\"description\" content=\"Las lentillas o lentes de contacto en verano se llevan muy bien. Disfruta de un verano m\u00e1s c\u00f3modo con lentes de contacto diarias de Soloptical.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/soloptical.net\/blog\/verano-y-lentes-de-contacto\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Verano c\u00f3modo con lentes de contacto - Blog a primera vista\" \/>\n<meta property=\"og:description\" content=\"Las lentillas o lentes de contacto en verano se llevan muy bien. Disfruta de un verano m\u00e1s c\u00f3modo con lentes de contacto diarias de Soloptical.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/soloptical.net\/blog\/verano-y-lentes-de-contacto\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog a primera vista\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-23T07:37:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-08T11:56:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2018\/12\/Lentillas-ojo-1024x683.jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ignacio del Valle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/soloptical.net\/blog\/#website\",\"url\":\"https:\/\/soloptical.net\/blog\/\",\"name\":\"Blog a primera vista\",\"description\":\"by soloptical\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/soloptical.net\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/soloptical.net\/blog\/verano-y-lentes-de-contacto\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2018\/12\/Lentillas-ojo.jpeg\",\"contentUrl\":\"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2018\/12\/Lentillas-ojo.jpeg\",\"width\":5616,\"height\":3744,\"caption\":\"Woman eye with contact lens applying, macro\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/soloptical.net\/blog\/verano-y-lentes-de-contacto\/#webpage\",\"url\":\"https:\/\/soloptical.net\/blog\/verano-y-lentes-de-contacto\/\",\"name\":\"Verano c\u00f3modo con lentes de contacto - Blog a primera vista\",\"isPartOf\":{\"@id\":\"https:\/\/soloptical.net\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/soloptical.net\/blog\/verano-y-lentes-de-contacto\/#primaryimage\"},\"datePublished\":\"2020-06-23T07:37:18+00:00\",\"dateModified\":\"2020-07-08T11:56:18+00:00\",\"author\":{\"@id\":\"https:\/\/soloptical.net\/blog\/#\/schema\/person\/be883171b2dc1bdfaaa718c3076badf5\"},\"description\":\"Las lentillas o lentes de contacto en verano se llevan muy bien. Disfruta de un verano m\u00e1s c\u00f3modo con lentes de contacto diarias de Soloptical.\",\"breadcrumb\":{\"@id\":\"https:\/\/soloptical.net\/blog\/verano-y-lentes-de-contacto\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/soloptical.net\/blog\/verano-y-lentes-de-contacto\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/soloptical.net\/blog\/verano-y-lentes-de-contacto\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/soloptical.net\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Verano c\u00f3modo con lentes de contacto\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/soloptical.net\/blog\/#\/schema\/person\/be883171b2dc1bdfaaa718c3076badf5\",\"name\":\"Ignacio del Valle\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/soloptical.net\/blog\/#personlogo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9ad4127768c84c42054454d8892fe489?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9ad4127768c84c42054454d8892fe489?s=96&d=mm&r=g\",\"caption\":\"Ignacio del Valle\"},\"url\":\"https:\/\/soloptical.net\/blog\/author\/ignacio-del-valle\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Verano c\u00f3modo con lentes de contacto - Blog a primera vista","description":"Las lentillas o lentes de contacto en verano se llevan muy bien. Disfruta de un verano m\u00e1s c\u00f3modo con lentes de contacto diarias de Soloptical.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/soloptical.net\/blog\/verano-y-lentes-de-contacto\/","og_locale":"es_ES","og_type":"article","og_title":"Verano c\u00f3modo con lentes de contacto - Blog a primera vista","og_description":"Las lentillas o lentes de contacto en verano se llevan muy bien. Disfruta de un verano m\u00e1s c\u00f3modo con lentes de contacto diarias de Soloptical.","og_url":"https:\/\/soloptical.net\/blog\/verano-y-lentes-de-contacto\/","og_site_name":"Blog a primera vista","article_published_time":"2020-06-23T07:37:18+00:00","article_modified_time":"2020-07-08T11:56:18+00:00","og_image":[{"url":"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2018\/12\/Lentillas-ojo-1024x683.jpeg"}],"twitter_card":"summary","twitter_misc":{"Escrito por":"Ignacio del Valle","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/soloptical.net\/blog\/#website","url":"https:\/\/soloptical.net\/blog\/","name":"Blog a primera vista","description":"by soloptical","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/soloptical.net\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","@id":"https:\/\/soloptical.net\/blog\/verano-y-lentes-de-contacto\/#primaryimage","inLanguage":"es","url":"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2018\/12\/Lentillas-ojo.jpeg","contentUrl":"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2018\/12\/Lentillas-ojo.jpeg","width":5616,"height":3744,"caption":"Woman eye with contact lens applying, macro"},{"@type":"WebPage","@id":"https:\/\/soloptical.net\/blog\/verano-y-lentes-de-contacto\/#webpage","url":"https:\/\/soloptical.net\/blog\/verano-y-lentes-de-contacto\/","name":"Verano c\u00f3modo con lentes de contacto - Blog a primera vista","isPartOf":{"@id":"https:\/\/soloptical.net\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/soloptical.net\/blog\/verano-y-lentes-de-contacto\/#primaryimage"},"datePublished":"2020-06-23T07:37:18+00:00","dateModified":"2020-07-08T11:56:18+00:00","author":{"@id":"https:\/\/soloptical.net\/blog\/#\/schema\/person\/be883171b2dc1bdfaaa718c3076badf5"},"description":"Las lentillas o lentes de contacto en verano se llevan muy bien. Disfruta de un verano m\u00e1s c\u00f3modo con lentes de contacto diarias de Soloptical.","breadcrumb":{"@id":"https:\/\/soloptical.net\/blog\/verano-y-lentes-de-contacto\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/soloptical.net\/blog\/verano-y-lentes-de-contacto\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/soloptical.net\/blog\/verano-y-lentes-de-contacto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/soloptical.net\/blog\/"},{"@type":"ListItem","position":2,"name":"Verano c\u00f3modo con lentes de contacto"}]},{"@type":"Person","@id":"https:\/\/soloptical.net\/blog\/#\/schema\/person\/be883171b2dc1bdfaaa718c3076badf5","name":"Ignacio del Valle","image":{"@type":"ImageObject","@id":"https:\/\/soloptical.net\/blog\/#personlogo","inLanguage":"es","url":"https:\/\/secure.gravatar.com\/avatar\/9ad4127768c84c42054454d8892fe489?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ad4127768c84c42054454d8892fe489?s=96&d=mm&r=g","caption":"Ignacio del Valle"},"url":"https:\/\/soloptical.net\/blog\/author\/ignacio-del-valle\/"}]}},"_links":{"self":[{"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/posts\/5968"}],"collection":[{"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/comments?post=5968"}],"version-history":[{"count":7,"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/posts\/5968\/revisions"}],"predecessor-version":[{"id":5979,"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/posts\/5968\/revisions\/5979"}],"wp:attachment":[{"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/media?parent=5968"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/categories?post=5968"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/tags?post=5968"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}