{"id":6685,"date":"2022-07-07T08:18:03","date_gmt":"2022-07-07T06:18:03","guid":{"rendered":"https:\/\/soloptical.net\/blog\/?p=6685"},"modified":"2022-07-07T10:25:49","modified_gmt":"2022-07-07T08:25:49","slug":"soloptical-tendencias-en-gafas-de-sol-2022","status":"publish","type":"post","link":"https:\/\/soloptical.net\/blog\/soloptical-tendencias-en-gafas-de-sol-2022\/","title":{"rendered":"Tendencias en gafas de sol verano 2022"},"content":{"rendered":"\n<p>\u00a1Ya sabemos las <strong>tendencias en gafas de sol<\/strong> para este verano! Los estilos de gafas de sol que triunfar\u00e1n esta temporada est\u00e1n en <a href=\"https:\/\/soloptical.net\/es\/\">Soloptical<\/a>. No puedes perderte esta informaci\u00f3n. Brilla este verano con las <strong>gafas de sol mujer<\/strong>. Protege tus ojos sin perder el glamour. Haz de tus <strong>gafas de sol tendencia 2022<\/strong>, el accesorio m\u00e1s llamativo de tu outfit. Visita <a href=\"https:\/\/soloptical.net\/es\/gafas-de-sol\/gafas-sol-mujer.html\">nuestro cat\u00e1logo<\/a> y sorpr\u00e9ndete<strong>.<\/strong> Ofrecemos las mejores marcas y los m\u00e1s modernos dise\u00f1os.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2022\/07\/SOLOPTICAL_Verano22_Lifestyle_00271-scaled.jpg\"><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2022\/07\/SOLOPTICAL_Verano22_Lifestyle_00271-1024x683.jpg\" alt=\"\" class=\"wp-image-6687\" srcset=\"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2022\/07\/SOLOPTICAL_Verano22_Lifestyle_00271-1024x683.jpg 1024w, https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2022\/07\/SOLOPTICAL_Verano22_Lifestyle_00271-300x200.jpg 300w, https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2022\/07\/SOLOPTICAL_Verano22_Lifestyle_00271-768x512.jpg 768w, https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2022\/07\/SOLOPTICAL_Verano22_Lifestyle_00271-1536x1024.jpg 1536w, https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2022\/07\/SOLOPTICAL_Verano22_Lifestyle_00271-2048x1365.jpg 2048w, https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2022\/07\/SOLOPTICAL_Verano22_Lifestyle_00271-980x653.jpg 980w, https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2022\/07\/SOLOPTICAL_Verano22_Lifestyle_00271-573x382.jpg 573w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<p>Quiz\u00e1s no sabes qu\u00e9 gafas de sol comprar, hay mucha variedad y no sabes por cual decidirte. Conocer las tendencias en<strong> gafas de sol<\/strong> te ayudar\u00e1 much\u00edsimo. No puedes permitirte comenzar el verano, sin un par de gafas muy a la moda. Para que logres ese objetivo, protejas tu vista de los rayos UV y luzcas espectacular. Te traemos toda la informaci\u00f3n sobre las tendencias en gafas de sol 2022. Sigue leyendo y ent\u00e9rate de todo.<\/p>\n\n\n\n<h2><strong>Tendencias en gafas de sol verano 2022<\/strong><\/h2>\n\n\n\n<p>Las lentes cl\u00e1sicas, como las gafas negras, estilo aviador o los Ray Ban Wayfarer. Son gafas que siempre se usar\u00e1n. Pero con las tendencias en gafas de sol de este a\u00f1o, corren el riesgo de ser desplazados en algunas ocasiones. Las gafas en tendencia para esta temporada son muy llamativas. Por lo que lo cl\u00e1sico, aunque nunca dejar\u00e1 de usarse, no es lo m\u00e1s en tendencia.<\/p>\n\n\n\n<p>Las tendencias en gafas de sol este a\u00f1o, se dejan llevar por las formas, colores y \u00e9pocas. Siguen la estela de la moda dopamina. Gafas de muchos colores, llamativas, con estampados y muy atrevidas. Que vienen a cambiar la sobriedad de las gafas usadas durante la pandemia. Si quieres estar a la moda, debes decantarte por aquellas originales, poco discretas, atrevidas y audaces.<\/p>\n\n\n\n<p>Tambi\u00e9n las monturas tienen sus caracter\u00edsticas en tendencias en gafas de sol. Los tonos llamativos est\u00e1n en boga y aquellas monturas de pasta gruesa. O las de color blanco que llaman mucho la atenci\u00f3n. En cuanto a los cristales, los tintados se llevar\u00e1n mucho. Colores rosa, lila, rojo, naranja estar\u00e1n en tendencia.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2022\/07\/MG_0697-1-scaled.jpg\"><img loading=\"lazy\" width=\"819\" height=\"1024\" src=\"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2022\/07\/MG_0697-1-819x1024.jpg\" alt=\"\" class=\"wp-image-6688\" srcset=\"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2022\/07\/MG_0697-1-819x1024.jpg 819w, https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2022\/07\/MG_0697-1-240x300.jpg 240w, https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2022\/07\/MG_0697-1-768x960.jpg 768w, https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2022\/07\/MG_0697-1-1229x1536.jpg 1229w, https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2022\/07\/MG_0697-1-1638x2048.jpg 1638w, https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2022\/07\/MG_0697-1-588x735.jpg 588w, https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2022\/07\/MG_0697-1-344x430.jpg 344w, https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2022\/07\/MG_0697-1-scaled.jpg 2048w\" sizes=\"(max-width: 819px) 100vw, 819px\" \/><\/a><\/figure>\n\n\n\n<p>Las m\u00e1s populares son las gafas con monturas en pasta de colores estridentes y llamativos como azul el\u00e9ctrico, fucsia, colores ne\u00f3n, rosa. Y por supuesto aquellas de montura blanca. Las formas rectangulares, tipo m\u00e1scaras, tama\u00f1o XL. Son las mas usadas esta temporada. Otras formas que ver\u00e1s con mucha frecuencia son las estilo <em>cat eye,<\/em> las de pantalla de estilos 70,80,90. Adem\u00e1s de aquellas con brillantes y monturas peque\u00f1as.<\/p>\n\n\n\n<p>Es un a\u00f1o para derrochar originalidad y ser atrevidos con el uso de las tendencias en gafas de sol. Se deja a un lado los colores aburridos, la sencilles y el minimalismo. Para dar paso al maximalismo, colores llamativos y dise\u00f1os originales.<\/p>\n\n\n\n<h2><strong>\u00bfCu\u00e1les son las caracter\u00edsticas de los modelos en tendencias en gafas de sol?<\/strong><\/h2>\n\n\n\n<p>Para que, a la hora de buscar las tendencias en gafas de sol, sepas que es lo que m\u00e1s se lleva de una forma clara. Te contamos que caracter\u00edsticas tienen las gafas que est\u00e1n en boga esta temporada.<\/p>\n\n\n\n<ul><li>Las gafas con toque vintage y ochenteras se llevar\u00e1n mucho.<\/li><li>Las gafas con monturas de pasta, unicolor muy llamativo. Estampadas, montura de pasta blanca. Se ver\u00e1n en las calles con frecuencia. Por supuesto las cl\u00e1sicas gafas de pasta negra que nunca dejan de usarse.<\/li><li>Tambi\u00e9n esta muy en boga las gafas multicolores. Los colores fucsias, los colores ne\u00f3n. El color rosa, verde, azul electr\u00f3nico, lila. E incluso las gafas bicolores son parte de las tendencias en gafas de sol.<\/li><li>Las monturas de metal y <em>cat eyes.<\/em><\/li><li>En cuanto al dise\u00f1o se siguen usando las gafas de aviador, pero el espectacular estilo rectangular, el transparente, redondas y hexagonal est\u00e1n de ultima. Y si algo ver\u00e1s durante este verano, son las gafas con dise\u00f1os XL.<\/li><\/ul>\n\n\n\n<h2><strong>\u00bfQu\u00e9 modelos comprar para estar dentro de las tendencias en gafas de sol de la temporada?<\/strong><\/h2>\n\n\n\n<p>Estos son los modelos en tendencia que ofrecen todas las <a href=\"https:\/\/soloptical.net\/es\/listado-de-opticas\/\">tiendas Soloptical<\/a>, para que luzcas la moda y todas las miradas volteen a verte. Brilla con nuestros modelos a los mejores precios y la mejor calidad.<\/p>\n\n\n\n<h3><strong>Cat eyes<\/strong><\/h3>\n\n\n\n<ul><li><strong><a href=\"https:\/\/soloptical.net\/es\/sv-vintage-497-830.html\">SXT Vintage 497-83<\/a><\/strong><\/li><\/ul>\n\n\n\n<p>Con un toque vintage, montura de metal y pasta, transparentes. Dar\u00e1n a tu mirada un toque de distinci\u00f3n. El efecto ojo de gato de anta\u00f1o, pero con una versi\u00f3n moderna y llamativa.<\/p>\n\n\n\n<ul><li><strong><a href=\"https:\/\/soloptical.net\/es\/catalogsearch\/result\/?q=+Vogue+VO5211-S+W65613\">Vogue VO5211-S W65613<\/a><\/strong><\/li><\/ul>\n\n\n\n<p>Montura de pasta animal print, cristales color marr\u00f3n. Elegancia y moda en un solo producto.<\/p>\n\n\n\n<h3><strong>Tendencias en gafas de sol Monturas de pasta<\/strong><\/h3>\n\n\n\n<h4><strong>Unicolor<\/strong><\/h4>\n\n\n\n<ul><li><strong><a href=\"https:\/\/soloptical.net\/es\/catalogsearch\/result\/?q=+Vogue+VO5211-S+W65613\">Vogue VO5287-S 27567E<\/a><\/strong><\/li><\/ul>\n\n\n\n<p>Originales, cristales fucsia y montura de pasta en un fucsia mas intenso. Si quieres que tu look sea el mejor. No dejes de probar estas maravillosas gafas.<\/p>\n\n\n\n<ul><li><strong><a href=\"https:\/\/soloptical.net\/es\/dolce-gabanna-dg6144-501-8g.html\">Dolce &amp; Gabanna DG6119 501\/8G<\/a><\/strong><\/li><\/ul>\n\n\n\n<p>En cl\u00e1sico color negro, montura de pasta, pero con un original dise\u00f1o, que hace que puedas lucir la elegancia y originalidad en un mismo look.<\/p>\n\n\n\n<h4><strong>Colores llamativos<\/strong><\/h4>\n\n\n\n<ul><li><strong><a href=\"https:\/\/soloptical.net\/es\/emporio-armani-2063-3217-8z.html\">Emporio Armani 2063 3217\/8Z<\/a><\/strong><\/li><\/ul>\n\n\n\n<p>Un hermoso color lavanda tanto en los cristales como en la montura. Esta dise\u00f1ada en una combinaci\u00f3n de pasta y metal. Son hermosos y atrevidos.<\/p>\n\n\n\n<ul><li><strong><a href=\"https:\/\/soloptical.net\/es\/venus-p-497-26222.html\">Venus P 497-262 17<\/a><\/strong><\/li><\/ul>\n\n\n\n<p>Gafas estilo mariposa con montura en pasta color rojo. La montura es completa y las gafas son polarizadas.<\/p>\n\n\n\n<h4><strong>Estampadas<\/strong><\/h4>\n\n\n\n<ul><li><strong><a href=\"https:\/\/soloptical.net\/es\/dolce-gabanna-dg4348-3229-8g.html\">Dolce &amp; Gabanna DG4348 3229\/8G<\/a><\/strong><\/li><\/ul>\n\n\n\n<p>Hermoso y original estampado, base negra y flores. Lentes degradadas, estilo mariposa, montura completa.<\/p>\n\n\n\n<ul><li><strong><a href=\"https:\/\/soloptical.net\/es\/prada-spr21x-2au-6s1.html\">Prada SPR21X 2AU-6S1<\/a><\/strong><\/li><\/ul>\n\n\n\n<p>Gafas cuadradas con montura color carey fabricada en pasta, montura completa, tama\u00f1o XL.<\/p>\n\n\n\n<h4><strong>Blancas<\/strong><\/h4>\n\n\n\n<ul><li><strong><a href=\"https:\/\/soloptical.net\/es\/catalogsearch\/result\/?q=Venus+497-201+C4\">Venus 497-201 C4<\/a><\/strong><\/li><\/ul>\n\n\n\n<p>Gafas rectangulares con montura en pasta transparente. Modernas, resistentes y de calidad.<\/p>\n\n\n\n<ul><li><strong><a href=\"https:\/\/soloptical.net\/es\/arnette-4265-2607-am.html\">Arnette 4265 2607\/AM<\/a><\/strong><\/li><\/ul>\n\n\n\n<p>Gafas rectangulares, montura blanca en pasta y cristales grises. Unisex. Un modelo vers\u00e1til que queda bien a todos los estilos.<\/p>\n\n\n\n<h3><strong>Dise\u00f1os y formas<\/strong><\/h3>\n\n\n\n<ul><li><strong><a href=\"https:\/\/soloptical.net\/es\/rayban-reg-aviator-gradient-rb3025-003-3f.html\">RayBan \u00ae Aviator Gradient RB3025 003\/3F<\/a><\/strong><\/li><\/ul>\n\n\n\n<p>Pertenece a la ultima colecci\u00f3n, un novedoso dise\u00f1o. Montura en metal plateado, cristales azul clara degradado.<\/p>\n\n\n\n<ul><li><strong><a href=\"https:\/\/soloptical.net\/es\/dolce-gabanna-dg2268-1344-13.html\">Dolce &amp; Gabanna DG2268 1344\/13<\/a><\/strong><\/li><\/ul>\n\n\n\n<p>Gafas rectangulares, montura de metal, lentes degradadas. Montura y cristales en color marr\u00f3n.<\/p>\n\n\n\n<ul><li><strong><a href=\"https:\/\/soloptical.net\/es\/catalogsearch\/result\/?q=+Vogue+VO5211-S+W65613\">Vogue VO5222S W44\/87<\/a><\/strong><\/li><\/ul>\n\n\n\n<p>Gafas poligonales en color negro con montura de pasta. Montura completa, cristales negros. Lentes elegantes, pero a la vez distintos, no convencionales.<\/p>\n\n\n\n<p>Estos son algunos modelos referenciales, visita nuestra tienda donde encontrar\u00e1s mucha m\u00e1s variedad.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1Ya sabemos las tendencias en gafas de sol para este verano! Los estilos de gafas de sol que triunfar\u00e1n esta temporada est\u00e1n en Soloptical. No puedes perderte esta informaci\u00f3n. Brilla este verano con las gafas de sol mujer. Protege tus ojos sin perder el glamour. Haz de tus gafas de sol tendencia 2022, el accesorio&nbsp;<a href=\"https:\/\/soloptical.net\/blog\/soloptical-tendencias-en-gafas-de-sol-2022\/\" class=\"read-more\">Continua leyendo<\/a><\/p>\n","protected":false},"author":16,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[80,253,265,2,1],"tags":[48,546,544,545],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tendencias en gafas de sol verano 2022 - Blog a primera vista<\/title>\n<meta name=\"description\" content=\"Entra en nuestro blog y en Soloptical te contamos las tendencias en gafas de sol de verano 2022 Ir a la moda nunca ha sido tan f\u00e1cil\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/soloptical.net\/blog\/soloptical-tendencias-en-gafas-de-sol-2022\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tendencias en gafas de sol verano 2022 - Blog a primera vista\" \/>\n<meta property=\"og:description\" content=\"Entra en nuestro blog y en Soloptical te contamos las tendencias en gafas de sol de verano 2022 Ir a la moda nunca ha sido tan f\u00e1cil\" \/>\n<meta property=\"og:url\" content=\"https:\/\/soloptical.net\/blog\/soloptical-tendencias-en-gafas-de-sol-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog a primera vista\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-07T06:18:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-07T08:25:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2022\/07\/SOLOPTICAL_Verano22_Lifestyle_00271-1024x683.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Clara P\u00e9rez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/soloptical.net\/blog\/#website\",\"url\":\"https:\/\/soloptical.net\/blog\/\",\"name\":\"Blog a primera vista\",\"description\":\"by soloptical\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/soloptical.net\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/soloptical.net\/blog\/soloptical-tendencias-en-gafas-de-sol-2022\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2022\/07\/SOLOPTICAL_Verano22_Lifestyle_00271-1024x683.jpg\",\"contentUrl\":\"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2022\/07\/SOLOPTICAL_Verano22_Lifestyle_00271-1024x683.jpg\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/soloptical.net\/blog\/soloptical-tendencias-en-gafas-de-sol-2022\/#webpage\",\"url\":\"https:\/\/soloptical.net\/blog\/soloptical-tendencias-en-gafas-de-sol-2022\/\",\"name\":\"Tendencias en gafas de sol verano 2022 - Blog a primera vista\",\"isPartOf\":{\"@id\":\"https:\/\/soloptical.net\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/soloptical.net\/blog\/soloptical-tendencias-en-gafas-de-sol-2022\/#primaryimage\"},\"datePublished\":\"2022-07-07T06:18:03+00:00\",\"dateModified\":\"2022-07-07T08:25:49+00:00\",\"author\":{\"@id\":\"https:\/\/soloptical.net\/blog\/#\/schema\/person\/199eeef2602704008f945da5969fffdb\"},\"description\":\"Entra en nuestro blog y en Soloptical te contamos las tendencias en gafas de sol de verano 2022 Ir a la moda nunca ha sido tan f\u00e1cil\",\"breadcrumb\":{\"@id\":\"https:\/\/soloptical.net\/blog\/soloptical-tendencias-en-gafas-de-sol-2022\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/soloptical.net\/blog\/soloptical-tendencias-en-gafas-de-sol-2022\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/soloptical.net\/blog\/soloptical-tendencias-en-gafas-de-sol-2022\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/soloptical.net\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tendencias en gafas de sol verano 2022\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/soloptical.net\/blog\/#\/schema\/person\/199eeef2602704008f945da5969fffdb\",\"name\":\"Clara P\u00e9rez\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/soloptical.net\/blog\/#personlogo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/fa81ed129be5bb27793174b1d3bcad9f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/fa81ed129be5bb27793174b1d3bcad9f?s=96&d=mm&r=g\",\"caption\":\"Clara P\u00e9rez\"},\"url\":\"https:\/\/soloptical.net\/blog\/author\/clara\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tendencias en gafas de sol verano 2022 - Blog a primera vista","description":"Entra en nuestro blog y en Soloptical te contamos las tendencias en gafas de sol de verano 2022 Ir a la moda nunca ha sido tan f\u00e1cil","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/soloptical.net\/blog\/soloptical-tendencias-en-gafas-de-sol-2022\/","og_locale":"es_ES","og_type":"article","og_title":"Tendencias en gafas de sol verano 2022 - Blog a primera vista","og_description":"Entra en nuestro blog y en Soloptical te contamos las tendencias en gafas de sol de verano 2022 Ir a la moda nunca ha sido tan f\u00e1cil","og_url":"https:\/\/soloptical.net\/blog\/soloptical-tendencias-en-gafas-de-sol-2022\/","og_site_name":"Blog a primera vista","article_published_time":"2022-07-07T06:18:03+00:00","article_modified_time":"2022-07-07T08:25:49+00:00","og_image":[{"url":"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2022\/07\/SOLOPTICAL_Verano22_Lifestyle_00271-1024x683.jpg"}],"twitter_card":"summary","twitter_misc":{"Escrito por":"Clara P\u00e9rez","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/soloptical.net\/blog\/#website","url":"https:\/\/soloptical.net\/blog\/","name":"Blog a primera vista","description":"by soloptical","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/soloptical.net\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","@id":"https:\/\/soloptical.net\/blog\/soloptical-tendencias-en-gafas-de-sol-2022\/#primaryimage","inLanguage":"es","url":"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2022\/07\/SOLOPTICAL_Verano22_Lifestyle_00271-1024x683.jpg","contentUrl":"https:\/\/soloptical.net\/blog\/wp-content\/uploads\/2022\/07\/SOLOPTICAL_Verano22_Lifestyle_00271-1024x683.jpg"},{"@type":"WebPage","@id":"https:\/\/soloptical.net\/blog\/soloptical-tendencias-en-gafas-de-sol-2022\/#webpage","url":"https:\/\/soloptical.net\/blog\/soloptical-tendencias-en-gafas-de-sol-2022\/","name":"Tendencias en gafas de sol verano 2022 - Blog a primera vista","isPartOf":{"@id":"https:\/\/soloptical.net\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/soloptical.net\/blog\/soloptical-tendencias-en-gafas-de-sol-2022\/#primaryimage"},"datePublished":"2022-07-07T06:18:03+00:00","dateModified":"2022-07-07T08:25:49+00:00","author":{"@id":"https:\/\/soloptical.net\/blog\/#\/schema\/person\/199eeef2602704008f945da5969fffdb"},"description":"Entra en nuestro blog y en Soloptical te contamos las tendencias en gafas de sol de verano 2022 Ir a la moda nunca ha sido tan f\u00e1cil","breadcrumb":{"@id":"https:\/\/soloptical.net\/blog\/soloptical-tendencias-en-gafas-de-sol-2022\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/soloptical.net\/blog\/soloptical-tendencias-en-gafas-de-sol-2022\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/soloptical.net\/blog\/soloptical-tendencias-en-gafas-de-sol-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/soloptical.net\/blog\/"},{"@type":"ListItem","position":2,"name":"Tendencias en gafas de sol verano 2022"}]},{"@type":"Person","@id":"https:\/\/soloptical.net\/blog\/#\/schema\/person\/199eeef2602704008f945da5969fffdb","name":"Clara P\u00e9rez","image":{"@type":"ImageObject","@id":"https:\/\/soloptical.net\/blog\/#personlogo","inLanguage":"es","url":"https:\/\/secure.gravatar.com\/avatar\/fa81ed129be5bb27793174b1d3bcad9f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fa81ed129be5bb27793174b1d3bcad9f?s=96&d=mm&r=g","caption":"Clara P\u00e9rez"},"url":"https:\/\/soloptical.net\/blog\/author\/clara\/"}]}},"_links":{"self":[{"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/posts\/6685"}],"collection":[{"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/comments?post=6685"}],"version-history":[{"count":3,"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/posts\/6685\/revisions"}],"predecessor-version":[{"id":6691,"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/posts\/6685\/revisions\/6691"}],"wp:attachment":[{"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/media?parent=6685"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/categories?post=6685"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/soloptical.net\/blog\/wp-json\/wp\/v2\/tags?post=6685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}